{"id":11339,"date":"2012-05-09T00:00:00","date_gmt":"2012-05-09T00:00:00","guid":{"rendered":"http:\/\/prensa.wp2.mendoza.gov.ar\/?p=11339"},"modified":"2012-05-09T00:00:00","modified_gmt":"2012-05-09T00:00:00","slug":"rentas-comenzo-sus-controles-en-la-playa-de-estacionamiento-de-casa-de-gobierno","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/rentas-comenzo-sus-controles-en-la-playa-de-estacionamiento-de-casa-de-gobierno\/","title":{"rendered":"Rentas comenz\u00f3 sus controles en la playa de estacionamiento de Casa de Gobierno"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p>La Direcci&oacute;n General de Rentas (DGR) comenz&oacute; esta ma&ntilde;ana con los operativos de control del Impuesto Inmobiliario y Automotor en la v&iacute;a p&uacute;blica y lo inici&oacute; en la playa de estacionamiento de Casa de Gobierno.<\/p>\n<p>Desde las 8.30 el director de Rentas, Claudio Gil, junto al director de Inteligencia Fiscal y Fiscalizaci&oacute;n, Mart&iacute;n Zirulnik, y un grupo de fiscalizadores realizaron controles en los autos estacionados en la playa oficial de Casa de Gobierno y en la playa que se encuentra  sobre el colector en calle Peltier.<\/p>\n<p>Ante la consulta respecto de los motivos por el cual se dio inicio a esta medida en Casa de Gobierno, el titular de Rentas, asegur&oacute; que responde a un &uacute;nico objetivo: &ldquo;dar el ejemplo&rdquo;, ya que, &ldquo;para lograr conciencia, es necesario comenzar desde adentro&rdquo;.<\/p>\n<p>En cuanto a los controles, desde el ente recaudador se&ntilde;alaron que los mismos se extendieron hasta pasadas las 12.30 del mediod&iacute;a en la zona de Casa de Gobierno. Paralelamente se realizaron operativos con la misma metodolog&iacute;a en Luj&aacute;n, Maip&uacute; y Godoy Cruz.<\/p>\n<p>En total se fiscalizaron 364 veh&iacute;culos en la v&iacute;a p&uacute;blica de los cuales 108 pertenecen a las inmediaciones del poder ejecutivo.<\/p>\n<p>En varias ocasiones se detect&oacute; falta de pago, por lo que se procedi&oacute; a pegar una calco que indica: &ldquo;El due&ntilde;o de este veh&iacute;culo es DEUDOR del impuesto AUTOMOTOR\/INMOBILIARIO&rdquo;. En el caso de que el contribuyente se encontrara al d&iacute;a en sus impuestos se lo premi&oacute; con una calco con la siguiente inscripci&oacute;n: &ldquo; yo pago mis impuestos&rdquo;.<\/p>\n<p><strong>Calcos<\/strong><\/p>\n<p>En el caso de observarse una deuda de $3.000 o m&aacute;s (puede tratarse de la sumatoria de deuda del Impuesto Inmobiliario y Automotor)  se procede a pegar las calcos en el parabrisas posterior, acompa&ntilde;ada de un acta de intimaci&oacute;n.<\/p>\n<p>En el caso de los rodados patentados en el 2012, que presenten deuda tambi&eacute;n se proceder&aacute; del modo antes mencionado.<\/p>\n<p>Los deudores deben regularizar su situaci&oacute;n en un plazo no mayor a los 10 d&iacute;as.<\/p>\n\n<p>Las verificaciones se realizaron a trav&eacute;s de una novedosa aplicaci&oacute;n telef&oacute;nica, en los celulares de los fiscalizadores, que les permiti&oacute; obtener, v&iacute;a internet, toda la informaci&oacute;n del contribuyente s&oacute;lo teniendo como referencia los datos de la patente del rodado.<\/p>\n\n<p><strong>Continuar&aacute;n los controles<\/strong><\/p>\n<p>Desde Rentas aseguraron que los controles se extender&aacute;n a toda la provincia durante el presente a&ntilde;o.<\/p>\n<p>Los operativos responden a una pol&iacute;tica de estado que busca mejorar la recaudaci&oacute;n y disminuir la evasi&oacute;n actual, como as&iacute; tambi&eacute;n,  fomentar la conciencia tributaria en la poblaci&oacute;n.<\/p>\n\n<p>El director de Rentas, Claudio Gil, pega una de las calcos de &ldquo;deudor&rdquo; en uno de los autos.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"La Direcci&oacute;n General de Rentas (DGR) comenz&oacute; esta ma&ntilde;ana con los operativos de control del Impuesto Inmobiliario y Automotor en la v&iacute;a p&uacute;blica y lo inici&oacute; en la playa de estacionamiento de Casa de Gobierno. Desde las 8.30 el director de Rentas, Claudio Gil, junto al director de Inteligencia Fiscal y Fiscalizaci&oacute;n, Mart&iacute;n Zirulnik, y&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/rentas-comenzo-sus-controles-en-la-playa-de-estacionamiento-de-casa-de-gobierno\/\"><\/a>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/11339"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=11339"}],"version-history":[{"count":0,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/11339\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=11339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=11339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=11339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}