{"id":140694,"date":"2018-07-01T06:35:08","date_gmt":"2018-07-01T09:35:08","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=140694"},"modified":"2018-07-02T09:09:45","modified_gmt":"2018-07-02T12:09:45","slug":"salud-como-condimentar-los-alimentos-para-disminuir-el-uso-de-sal","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/salud-como-condimentar-los-alimentos-para-disminuir-el-uso-de-sal\/","title":{"rendered":"Salud: c\u00f3mo condimentar los alimentos para disminuir el uso de sal"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><em>Disminuir el consumo de sal en nuestra alimentaci&oacute;n cotidiana es una de las principales recomendaciones para mantener una buena salud. El uso del lim&oacute;n, el vinagre y las arom&aacute;ticas debe estar siempre presente al preparar y sazonar los alimentos.<\/em><\/p>\n<p>As&iacute; podemos utilizar el tomillo para perfumar salsas, pescados, carnes, quesos y conserva de alimentos. Las hojas y tallos de la albahaca, principal componente de la salsa pesto, sirven para aromatizar carnes, pescados o ensaladas.<\/p>\n<p>El or&eacute;gano, del cual somos principales productores a nivel pa&iacute;s, combina con carnes, pollos, verduras frescas o asadas, quesos, escabeches, salsas, pastas y pizzas. Se utiliza como aromatidor de aceites, mantecas y conservas.<\/p>\n<p>El laurel se emplea en sopas, guisos y estofados, siendo su uso m&aacute;s difundido en tucos para acompa&ntilde;ar pastas. Realza carnes, pastas, vegetales y para marinar pescados. Sus hojas son simples, arom&aacute;ticas y de color verde oscuro lustroso.<\/p>\n<p>El perejil acompa&ntilde;a muy bien m&uacute;ltiples preparaciones crudas&nbsp;y cocidas: ensaladas, ali&ntilde;os, aderezos, salsas, pestos y carnes rojas&nbsp;o blancas.<\/p>\n<p>En tanto, las hojas frescas o secas del romero se emplean para condimentar asados y carnes como pollo, cordero y cerdo. Tambi&eacute;n para aromatizar guisos,&nbsp;papas y panes. El pollo al romero es uno de los platos en que esta arom&aacute;tica se luce muy&nbsp; bien.<\/p>\n<p>La menta est&aacute; presente, sobre todo, en la cocina &aacute;rabe e inglesa. Aromatiza platos como carnes rojas y cordero. Su esencia se utiliza en perfumer&iacute;a y en la elaboraci&oacute;n de licores&nbsp;y caramelos.<\/p>\n<p><strong>C&oacute;mo conservarlas<\/strong><\/p>\n<p><strong>Congeladas<\/strong>: picar, limpiar y congelar en cubitos de agua o de caldo.<\/p>\n<p><strong>Secas:<\/strong> elegir hierbas frescas y sanas. Secar sin lavar, atar en peque&ntilde;os ramos y colgar boca abajo<\/p>\n<p><strong>Lavadas y secas<\/strong> entre hojas de papel absorbente.<\/p>\n<p><strong>Lavadas y bien secas<\/strong> en recipientes opacos con aceite o vinagre.<\/p>\n<p><strong>En sal<\/strong>, alternando en un recipiente capas de sal y de hierbas.<\/p>\n<p><strong>Un secreto<\/strong><\/p>\n<p>Para que no pierdan sus propiedades y conserven la intensidad de sus aromas, se recomienda a&ntilde;adirlas a las comidas en los &uacute;ltimos minutos de cocci&oacute;n.<\/p>\n\n        <style type='text\/css'>\n            #gallery-1 {\n                margin: auto;\n            }\n            #gallery-1 .gallery-item {\n                float: left;\n                margin-top: 10px;\n\n                width: auto;}\n            #gallery-1 img {\n                border: 0px none;\n            }\n            #gallery-1 .gallery-caption {\n                margin-left: 0;\n            }\n        <\/style>\n<script>\njQuery(document).ready(function($) {\n  jQuery('div.gallery-item').hover(function(){\n     \/\/jQuery(this).fadeIn().siblings(':not(.modal)').fadeTo( 'slow' , 0.2);\n     jQuery(this).siblings(':not(.modal)').fadeTo( 'fast' , 0.2);\n     jQuery(this).fadeTo( 'slow' , 1);\n  },function(){\n     \/\/$(this).siblings().andSelf().fadeTo( 'slow' , 1);\n  });\n  jQuery('#gallery-1').on('mouseleave',function(){\n    jQuery('div.gallery-item').fadeTo( 'fast' , 1);\n  })\n});\n<\/script>\n        <!-- see gallery_shortcode() in wp-includes\/media.php -->\n        <h3>GALERIA<\/h3>\n        <div id='gallery-1' class='gallery galleryid-140694'><div class='gallery-item' data-toggle='modal' data-target='#140701' id='r140701'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/0_Pizarras-huerto-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"140701\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a href='https:\/\/www.mendoza.gov.ar\/prensa\/salud-como-condimentar-los-alimentos-para-disminuir-el-uso-de-sal\/0_pizarras-huerto\/'><img width=\"700\" height=\"466\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/0_Pizarras-huerto-700x466.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/0_Pizarras-huerto-700x466.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/0_Pizarras-huerto-250x166.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/0_Pizarras-huerto-120x80.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/0_Pizarras-huerto.jpg 715w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#140700\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div><div class='gallery-item' data-toggle='modal' data-target='#140700' id='r140700'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/hierbas-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"140700\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#140701\"><i class=\"text-white fa fa-chevron-left fa-4x\"><\/i><\/a><a href='https:\/\/www.mendoza.gov.ar\/prensa\/salud-como-condimentar-los-alimentos-para-disminuir-el-uso-de-sal\/hierbas\/'><img width=\"700\" height=\"350\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/hierbas-700x350.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/hierbas-700x350.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/hierbas-250x125.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/hierbas-768x384.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/hierbas-120x60.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/06\/hierbas.jpg 959w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#140701\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div>\n            <br style='clear: both;' \/>\n        <\/div>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Disminuir el consumo de sal en nuestra alimentaci&oacute;n cotidiana es una de las principales recomendaciones para mantener una buena salud. El uso del lim&oacute;n, el vinagre y las arom&aacute;ticas debe estar siempre presente al preparar y sazonar los alimentos. As&iacute; podemos utilizar el tomillo para perfumar salsas, pescados, carnes, quesos y conserva de alimentos. Las&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/salud-como-condimentar-los-alimentos-para-disminuir-el-uso-de-sal\/\"><\/a>","protected":false},"author":68,"featured_media":140701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[15,1791],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/140694"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=140694"}],"version-history":[{"count":3,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/140694\/revisions"}],"predecessor-version":[{"id":140747,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/140694\/revisions\/140747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/140701"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=140694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=140694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=140694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}