{"id":142914,"date":"2018-07-23T10:29:12","date_gmt":"2018-07-23T13:29:12","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=142914"},"modified":"2018-07-23T11:47:26","modified_gmt":"2018-07-23T14:47:26","slug":"reconocieron-a-un-efectivo-penitenciario-caido-en-un-acto-de-servicio","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/reconocieron-a-un-efectivo-penitenciario-caido-en-un-acto-de-servicio\/","title":{"rendered":"Reconocieron a un efectivo penitenciario ca\u00eddo en servicio"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p style=\"font-weight: 400\"><em>Se trata de Ercilio Javier Videla, quien hace 25 a&ntilde;os perdi&oacute; la vida mientras cumpl&iacute;a funciones como agente penitenciario.<\/em><\/p>\n<p style=\"font-weight: 400\">El ministro de Seguridad, Gianni Venier, junto con el director general del Servicio Penitenciario, Eduardo Orellana, y otras autoridades participaron en el acto que tuvo como motivo principal el reconocimiento post mortem del suboficial ayudante de Cuarta Ercilio Javier Videla.<\/p>\n<p style=\"font-weight: 400\">El 23 de febrero pasado se cumplieron 25 a&ntilde;os de aquel tr&aacute;gico episodio ocurrido en Boulogne Sur Mer que provoc&oacute; la muerte de Videla. De all&iacute;, la necesidad de destacar y reconocer a dicho personal.<\/p>\n<p style=\"font-weight: 400\">Durante el acto se ley&oacute; la Resoluci&oacute;n 926\/18, la cual establece la necesidad de fijar el 19 de julio para reconocer y recordar al personal penitenciario ca&iacute;do en el cumplimiento del deber institucional. La resoluci&oacute;n proclama adem&aacute;s que, ante esta situaci&oacute;n, las instituciones deben tener la obligaci&oacute;n de reconocimiento a su acci&oacute;n y memoria, para destacar el valor puesto por parte de los efectivos a lo largo de su carrera.<\/p>\n<p style=\"font-weight: 400\">El prefecto Gabriel Salom&oacute;n, actual director del Complejo San Felipe y compa&ntilde;ero de promoci&oacute;n de Videla, expres&oacute; que &ldquo;con estas acciones reafirmamos nuestra vocaci&oacute;n de servicio, sinti&eacute;ndonos orgullosos y halagados con la funci&oacute;n diaria que s&oacute;lo es comprensible para quienes tienen que afrontar situaciones dif&iacute;ciles y de alto riesgo&rdquo;.<\/p>\n<p style=\"font-weight: 400\">&ldquo;Agradezco a quienes han llevado a cabo este deseo de establecer un d&iacute;a para reconocer a los compa&ntilde;eros ca&iacute;dos. Es por ello que pido a todos los superiores que no s&oacute;lo gu&iacute;en sino que acompa&ntilde;en la labor de su gente, ya que son ellos quienes llevar&aacute;n a nuestra querida instituci&oacute;n a ser un fiel servidor p&uacute;blico&rdquo;, indic&oacute; Salom&oacute;n.<\/p>\n<p style=\"font-weight: 400\">El padre Marcelo de Benedectis destac&oacute; el avance producido en Servicio Penitenciario provincial: &ldquo;Esta memoria se enmarca no s&oacute;lo en un camino de identidad sino tambi&eacute;n de pertenencia, lo cual resulta sumamente necesario para la misi&oacute;n&rdquo;.<\/p>\n<p style=\"font-weight: 400\"><strong>Recordatorio para Nelson Haro<\/strong><\/p>\n<p style=\"font-weight: 400\">Durante el acto, las autoridades recordaron adem&aacute;s a Nelson Haro, otro efectivo fallecido en el cumplimiento de sus funciones. Destacaron &ldquo;la importancia de establecer este d&iacute;a para reconocer a nuestros camaradas nos obliga a recordar tambi&eacute;n a Cristi&aacute;n Haro, quien tambi&eacute;n ser&aacute; reconocido por parte de todo el Servicio Penitenciario de Mendoza&rdquo;.<\/p>\n\n        <style type='text\/css'>\n            #gallery-1 {\n                margin: auto;\n            }\n            #gallery-1 .gallery-item {\n                float: left;\n                margin-top: 10px;\n\n                width: auto;}\n            #gallery-1 img {\n                border: 0px none;\n            }\n            #gallery-1 .gallery-caption {\n                margin-left: 0;\n            }\n        <\/style>\n<script>\njQuery(document).ready(function($) {\n  jQuery('div.gallery-item').hover(function(){\n     \/\/jQuery(this).fadeIn().siblings(':not(.modal)').fadeTo( 'slow' , 0.2);\n     jQuery(this).siblings(':not(.modal)').fadeTo( 'fast' , 0.2);\n     jQuery(this).fadeTo( 'slow' , 1);\n  },function(){\n     \/\/$(this).siblings().andSelf().fadeTo( 'slow' , 1);\n  });\n  jQuery('#gallery-1').on('mouseleave',function(){\n    jQuery('div.gallery-item').fadeTo( 'fast' , 1);\n  })\n});\n<\/script>\n        <!-- see gallery_shortcode() in wp-includes\/media.php -->\n        <h3>GALERIA<\/h3>\n        <div id='gallery-1' class='gallery galleryid-142914'><div class='gallery-item' data-toggle='modal' data-target='#142915' id='r142915'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4246-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"142915\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a href='https:\/\/www.mendoza.gov.ar\/prensa\/reconocieron-a-un-efectivo-penitenciario-caido-en-un-acto-de-servicio\/dsc_4246\/'><img width=\"700\" height=\"467\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4246-700x467.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4246-700x467.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4246-250x167.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4246-768x512.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4246-120x80.jpg 120w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#142916\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div><div class='gallery-item' data-toggle='modal' data-target='#142916' id='r142916'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4264-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"142916\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#142915\"><i class=\"text-white fa fa-chevron-left fa-4x\"><\/i><\/a><a href='https:\/\/www.mendoza.gov.ar\/prensa\/reconocieron-a-un-efectivo-penitenciario-caido-en-un-acto-de-servicio\/dsc_4264\/'><img width=\"700\" height=\"467\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4264-700x467.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4264-700x467.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4264-250x167.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4264-768x512.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4264-120x80.jpg 120w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#142917\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div><div class='gallery-item' data-toggle='modal' data-target='#142917' id='r142917'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4295-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"142917\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#142916\"><i class=\"text-white fa fa-chevron-left fa-4x\"><\/i><\/a><a href='https:\/\/www.mendoza.gov.ar\/prensa\/reconocieron-a-un-efectivo-penitenciario-caido-en-un-acto-de-servicio\/dsc_4295\/'><img width=\"700\" height=\"467\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4295-700x467.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4295-700x467.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4295-250x167.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4295-768x512.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4295-120x80.jpg 120w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#142918\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div><div class='gallery-item' data-toggle='modal' data-target='#142918' id='r142918'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4321-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"142918\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#142917\"><i class=\"text-white fa fa-chevron-left fa-4x\"><\/i><\/a><a href='https:\/\/www.mendoza.gov.ar\/prensa\/reconocieron-a-un-efectivo-penitenciario-caido-en-un-acto-de-servicio\/dsc_4321\/'><img width=\"700\" height=\"467\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4321-700x467.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4321-700x467.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4321-250x167.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4321-768x512.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/07\/DSC_4321-120x80.jpg 120w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#142915\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div>\n            <br style='clear: both;' \/>\n        <\/div>\n\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Se trata de Ercilio Javier Videla, quien hace 25 a&ntilde;os perdi&oacute; la vida mientras cumpl&iacute;a funciones como agente penitenciario. El ministro de Seguridad, Gianni Venier, junto con el director general del Servicio Penitenciario, Eduardo Orellana, y otras autoridades participaron en el acto que tuvo como motivo principal el reconocimiento post mortem del suboficial ayudante de&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/reconocieron-a-un-efectivo-penitenciario-caido-en-un-acto-de-servicio\/\"><\/a>","protected":false},"author":77,"featured_media":142918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/142914"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=142914"}],"version-history":[{"count":4,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/142914\/revisions"}],"predecessor-version":[{"id":142922,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/142914\/revisions\/142922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/142918"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=142914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=142914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=142914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}