{"id":144059,"date":"2018-07-31T11:04:36","date_gmt":"2018-07-31T14:04:36","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=144059"},"modified":"2018-07-31T12:21:03","modified_gmt":"2018-07-31T15:21:03","slug":"entregaron-equipos-estructurales-para-los-bomberos-de-la-delegacion-sur","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/entregaron-equipos-estructurales-para-los-bomberos-de-la-delegacion-sur\/","title":{"rendered":"Entregaron equipos estructurales para los bomberos de la delegaci\u00f3n Sur"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p lang=\"zxx\"><em>Los 10 equipos representan una inversi&oacute;n de $468.000. Tambi&eacute;n se entregaron 35 equipos en&nbsp;el Gran Mendoza, Valle de Uco y la zona Este. Constan de&nbsp;traje, campera, pantal&oacute;n, guantes, botas y capucha ign&iacute;fuga o monjita.<\/em><\/p>\n<p lang=\"zxx\">El director de Bomberos de la Polic&iacute;a de Mendoza, Eduardo Mu&ntilde;oz, entreg&oacute; 10 equipos estructurales a la Delegaci&oacute;n de la zona Sur.<\/p>\n<p lang=\"zxx\">Cada equipo tiene un costo aproximado de $46.800, por lo que el total de la inversi&oacute;n se acerca a medio mill&oacute;n de pesos.<\/p>\n<p lang=\"zxx\">La semana pasada se presentaron los 35 equipos, de los cuales 13 se entregaron a el Gran Mendoza, 6 al Valle de Uco y 6 para la zona Este.<\/p>\n<p lang=\"zxx\">Cada equipo consta de traje, campera, pantal&oacute;n, guantes, botas y capucha ign&iacute;fuga o monjita.<\/p>\n<p lang=\"zxx\"><b>Caracter&iacute;sticas de los equipos estructurales<\/b><\/p>\n<p lang=\"zxx\">Los equipos son indispensables para las actividades que realizan los bomberos, ya que est&aacute;n confeccionados co<em>n twin system,<\/em>&nbsp;que tiene un tejido con una excelente protecci&oacute;n en las altas temperaturas, mayor flexibilidad y mayor resistencia a los rayos UV y 40% m&aacute;s de resistencia mec&aacute;nica que los tejidos tradicionales. Adem&aacute;s, cuenta con terminaciones XPS (polietileno extruido), que hacen al tejido a prueba de productos derivados del petr&oacute;leo y a la nafta sin plomo.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Los 10 equipos representan una inversi&oacute;n de $468.000. Tambi&eacute;n se entregaron 35 equipos en&nbsp;el Gran Mendoza, Valle de Uco y la zona Este. Constan de&nbsp;traje, campera, pantal&oacute;n, guantes, botas y capucha ign&iacute;fuga o monjita. El director de Bomberos de la Polic&iacute;a de Mendoza, Eduardo Mu&ntilde;oz, entreg&oacute; 10 equipos estructurales a la Delegaci&oacute;n de la zona&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/entregaron-equipos-estructurales-para-los-bomberos-de-la-delegacion-sur\/\"><\/a>","protected":false},"author":62,"featured_media":144060,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/144059"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=144059"}],"version-history":[{"count":5,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/144059\/revisions"}],"predecessor-version":[{"id":144085,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/144059\/revisions\/144085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/144060"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=144059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=144059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=144059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}