{"id":147800,"date":"2018-08-23T13:05:05","date_gmt":"2018-08-23T16:05:05","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=147800"},"modified":"2018-08-23T13:12:20","modified_gmt":"2018-08-23T16:12:20","slug":"seguridad-brinda-recomendaciones-para-evitar-robos-en-zonas-rurales","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/seguridad-brinda-recomendaciones-para-evitar-robos-en-zonas-rurales\/","title":{"rendered":"Seguridad brinda recomendaciones para evitar robos en zonas rurales"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p style=\"font-weight: 400\"><em>No guardar importantes sumas de dinero en la vivienda y evitar dejar puertas abiertas son algunos de los cuidados a tener en cuenta.<\/em><\/p>\n<p style=\"font-weight: 400\">Autoridades del Ministerio de Seguridad brindan una serie de medidas que buscan prevenir y brindar protecci&oacute;n a todas las personas que viven en zonas rurales y que pueden ser v&iacute;ctimas de un delito.<\/p>\n<p style=\"font-weight: 400\">Entre las principales recomendaciones se aconseja evitar tener grandes cantidades de dinero en la vivienda y, en el caso de pagar sueldos a empleados, realizarlo con formas de pago alternativas.<\/p>\n<p style=\"font-weight: 400\">Otro de los consejos es guardar en galpones las maquinarias, implementos agr&iacute;colas, elementos de bodegas y herramientas, y los animales, en corrales vallados y bien iluminados.<\/p>\n<p style=\"font-weight: 400\">Hay que evitar dejar&nbsp;puertas sin llave o tranqueras abiertas sobre todo por la noche y no divulgar a persona desconocida y que no sea de la familia la realizaci&oacute;n de transacciones de bienes, cobros de productos, sueldos o herencias.<\/p>\n<p style=\"font-weight: 400\">En este sentido, jefes de la cartera de Seguridad recomiendan realizar una red de comunicaci&oacute;n, por ejemplo en <em>whatsapp<\/em>, con aquellos vecinos de confianza y polic&iacute;as para que est&eacute;n comunicados ante cualquier situaci&oacute;n extra&ntilde;a.<\/p>\n<p style=\"font-weight: 400\">Ante cualquier emergencia, llamar de inmediato al 911 o dirigirse a la comisar&iacute;a m&aacute;s cercana.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"No guardar importantes sumas de dinero en la vivienda y evitar dejar puertas abiertas son algunos de los cuidados a tener en cuenta. Autoridades del Ministerio de Seguridad brindan una serie de medidas que buscan prevenir y brindar protecci&oacute;n a todas las personas que viven en zonas rurales y que pueden ser v&iacute;ctimas de un&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/seguridad-brinda-recomendaciones-para-evitar-robos-en-zonas-rurales\/\"><\/a>","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/147800"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=147800"}],"version-history":[{"count":3,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/147800\/revisions"}],"predecessor-version":[{"id":147828,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/147800\/revisions\/147828"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=147800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=147800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=147800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}