{"id":147982,"date":"2018-08-24T10:39:00","date_gmt":"2018-08-24T13:39:00","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=147982"},"modified":"2018-08-24T14:28:50","modified_gmt":"2018-08-24T17:28:50","slug":"capacitaran-a-bomberos-y-personal-de-policia-cientifica","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/capacitaran-a-bomberos-y-personal-de-policia-cientifica\/","title":{"rendered":"Capacitar\u00e1n a bomberos y personal de Polic\u00eda Cient\u00edfica"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p lang=\"zxx\">Ma&ntilde;ana, a partir de las 9, en Las Heras, personal de la Direcci&oacute;n de Bomberos y Polic&iacute;a Cient&iacute;fica del Ministerio de Seguridad podr&aacute; participar de un taller sobre &ldquo;Investigaci&oacute;n de incendios en automotores&rdquo;.<\/p>\n<p lang=\"zxx\">Se capacitar&aacute; sobre Valoraci&oacute;n de indicios, Inspecci&oacute;n ocular y Coordinaci&oacute;n de labores seg&uacute;n &aacute;mbito de incumbencia.<\/p>\n<p lang=\"zxx\">Este taller ser&aacute; impartido por Gustavo Escudero, perteneciente a la Polic&iacute;a Cient&iacute;fica, y es parte de un programa de capacitaci&oacute;n que llevan en conjunto ambas instituciones.<\/p>\n<p lang=\"zxx\"><img loading=\"lazy\" class=\"alignnone wp-image-147985 size-large img-responsive center-block\" src=\"https:\/\/www.mendoza.gov.ar\/prensa\/wp-content\/uploads\/sites\/5\/2018\/08\/Workshop-700x701.jpg\" alt=\"\" width=\"700\" height=\"701\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/08\/Workshop-700x701.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/08\/Workshop-150x150.jpg 150w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/08\/Workshop-250x250.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/08\/Workshop-768x769.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/08\/Workshop-120x120.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/08\/Workshop.jpg 1279w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Ma&ntilde;ana, a partir de las 9, en Las Heras, personal de la Direcci&oacute;n de Bomberos y Polic&iacute;a Cient&iacute;fica del Ministerio de Seguridad podr&aacute; participar de un taller sobre &ldquo;Investigaci&oacute;n de incendios en automotores&rdquo;. Se capacitar&aacute; sobre Valoraci&oacute;n de indicios, Inspecci&oacute;n ocular y Coordinaci&oacute;n de labores seg&uacute;n &aacute;mbito de incumbencia. Este taller ser&aacute; impartido por Gustavo&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/capacitaran-a-bomberos-y-personal-de-policia-cientifica\/\"><\/a>","protected":false},"author":62,"featured_media":147985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/147982"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=147982"}],"version-history":[{"count":6,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/147982\/revisions"}],"predecessor-version":[{"id":148059,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/147982\/revisions\/148059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/147985"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=147982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=147982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=147982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}