{"id":149035,"date":"2018-08-30T14:34:35","date_gmt":"2018-08-30T17:34:35","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=149035"},"modified":"2018-08-30T17:21:52","modified_gmt":"2018-08-30T20:21:52","slug":"seguridad-recomienda-cuidados-a-la-hora-de-manejar-una-moto","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/seguridad-recomienda-cuidados-a-la-hora-de-manejar-una-moto\/","title":{"rendered":"Seguridad recomienda cuidados al conducir en moto"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><em>Usar el casco, respetar las velocidades permitidas y evitar manejar el veh&iacute;culo cuando se haya ingerido alcohol son algunas de las recomendaciones a tener en cuenta.<\/em><\/p>\n<p>Debido a la cantidad de accidentes donde pierden la vida j&oacute;venes y adultos al mando de una moto, el Ministerio de Seguridad brinda medidas a seguir para evitar este tipo de siniestros.<\/p>\n<p>Entre las recomendaciones a tener en cuenta, se aconseja usar siempre el casco, respetar las velocidades permitidas y nunca manejar si se ha ingerido alcohol.<\/p>\n<p>En este sentido, especialistas en seguridad vial aseguran que la&nbsp; concientizaci&oacute;n y el respeto a las normas de tr&aacute;nsito son fundamentales al conducir una moto.<\/p>\n<p>Otros de los cuidados son no exceder el n&uacute;mero de ocupantes en el veh&iacute;culo, nunca llevar a ni&ntilde;os peque&ntilde;os, evitar realizar maniobras peligrosas y respetar los sem&aacute;foros y las se&ntilde;ales de tr&aacute;nsito.<\/p>\n<p>Tambi&eacute;n es importante indicar con anticipaci&oacute;n los giros o cambios de carril y mantener distancia con el veh&iacute;culo que lo antecede.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Usar el casco, respetar las velocidades permitidas y evitar manejar el veh&iacute;culo cuando se haya ingerido alcohol son algunas de las recomendaciones a tener en cuenta. Debido a la cantidad de accidentes donde pierden la vida j&oacute;venes y adultos al mando de una moto, el Ministerio de Seguridad brinda medidas a seguir para evitar este&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/seguridad-recomienda-cuidados-a-la-hora-de-manejar-una-moto\/\"><\/a>","protected":false},"author":63,"featured_media":149036,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/149035"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=149035"}],"version-history":[{"count":3,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/149035\/revisions"}],"predecessor-version":[{"id":149062,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/149035\/revisions\/149062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/149036"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=149035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=149035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=149035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}