{"id":150987,"date":"2018-09-11T13:15:58","date_gmt":"2018-09-11T16:15:58","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=150987"},"modified":"2018-09-11T15:59:37","modified_gmt":"2018-09-11T18:59:37","slug":"diversion-nocturna-clausuro-168-fiestas-clandestinas-en-lo-que-va-del-2018","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/diversion-nocturna-clausuro-168-fiestas-clandestinas-en-lo-que-va-del-2018\/","title":{"rendered":"Diversi\u00f3n Nocturna clausur\u00f3 168 fiestas clandestinas en lo que va del 2018"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p style=\"font-weight: 400\"><em>El Ministerio de Seguridad cuenta con un 0800 para realizar denuncias sobre&nbsp;irregularidades en lugares nocturnos y eventos privados que no tengan habilitaci&oacute;n.<\/em><\/p>\n<p style=\"font-weight: 400\">La Subdirecci&oacute;n de Control de Eventos y Locales de Esparcimiento, dependiente del Ministerio de Seguridad, ha clausurado en lo que va del a&ntilde;o 168 fiestas sin autorizaci&oacute;n. Los ceses de actividad de los eventos se realizaron entre enero y setiembre.<\/p>\n<p style=\"font-weight: 400\">Entre los casos de clausuras de fiestas clandestinas, el 3 de setiembre, en calle Sarmiento del departamento de Guaymall&eacute;n, se realiz&oacute; el cese de actividad de un evento, cuyo organizador ten&iacute;a medidas pendientes ante la Justicia, por lo que fue detenido.<\/p>\n<p style=\"font-weight: 400\">En cuanto a los objetivos, las autoridades buscan&nbsp;evitar la presencia de menores en locales bailables para mayores y la venta de bebidas alcoh&oacute;licas en eventos M-17 y matin&eacute;s.<\/p>\n<p style=\"font-weight: 400\">Para lograr este fin, el personal de&nbsp;Diversi&oacute;n Nocturna cuenta con un 0800&nbsp;para que vecinos denuncien irregularidades en lugares nocturnos y eventos privados que no est&eacute;n habilitados. Se trata del 0800 222 0900, disponible todos los d&iacute;as las 24 horas.<\/p>\n<p style=\"font-weight: 400\"><strong>Reglamentaci&oacute;n<\/strong><\/p>\n<p style=\"font-weight: 400\">Los inspectores controlan&nbsp;que los j&oacute;venes mayores de 18 a&ntilde;os no ingresen a los locales bailables despu&eacute;s de las 2.30 y que&nbsp;los due&ntilde;os de los boliches respeten el horario de cierre de barra y el de cierre del lugar: 4.30 y 6.30 horas respectivamente.<\/p>\n<p style=\"font-weight: 400\">En cuanto a los eventos y locales&nbsp;M-17,&nbsp;podr&aacute;n ingresar&nbsp;menores de 16 y 17 a&ntilde;os&nbsp;y el&nbsp;horario m&aacute;ximo de ingreso ser&aacute; a las 00.00 y el cierre est&aacute; dispuesto para las 5 de la ma&ntilde;ana. Mientras que a una matin&eacute; podr&aacute;n ingresar&nbsp;menores de 12 a 15 a&ntilde;os. El&nbsp;horario m&aacute;ximo de ingreso es a las 20 y el cierre se dispone para las 00.00.<\/p>\n<p style=\"font-weight: 400\">En estos dos &uacute;ltimos casos est&aacute; prohibido el ingreso, venta, expendio y consumo de bebidas alcoh&oacute;licas.<\/p>\n<p style=\"font-weight: 400\">\n<\/p><\/body><\/html>\n","protected":false},"excerpt":{"rendered":"El Ministerio de Seguridad cuenta con un 0800 para realizar denuncias sobre&nbsp;irregularidades en lugares nocturnos y eventos privados que no tengan habilitaci&oacute;n. La Subdirecci&oacute;n de Control de Eventos y Locales de Esparcimiento, dependiente del Ministerio de Seguridad, ha clausurado en lo que va del a&ntilde;o 168 fiestas sin autorizaci&oacute;n. Los ceses de actividad de los&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/diversion-nocturna-clausuro-168-fiestas-clandestinas-en-lo-que-va-del-2018\/\"><\/a>","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/150987"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=150987"}],"version-history":[{"count":4,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/150987\/revisions"}],"predecessor-version":[{"id":151010,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/150987\/revisions\/151010"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=150987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=150987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=150987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}