{"id":151172,"date":"2018-09-12T13:30:32","date_gmt":"2018-09-12T16:30:32","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=151172"},"modified":"2018-09-12T14:28:29","modified_gmt":"2018-09-12T17:28:29","slug":"cuidados-a-la-hora-de-manejar-en-dias-de-lluvias","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/cuidados-a-la-hora-de-manejar-en-dias-de-lluvias\/","title":{"rendered":"Cuidados al manejar en d\u00edas de lluvia"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p style=\"font-weight: 400\"><em>Seguridad brinda recomendaciones para prevenir accidentes viales con la presencia de esa contingencia clim&aacute;tica.<\/em><\/p>\n<p style=\"font-weight: 400\">Ante el pron&oacute;stico de posibles lluvias que pueden registrarse en algunas zonas de la provincia, el Ministerio de Seguridad brinda una serie de recomendaciones para que conductores de veh&iacute;culos no sufran accidentes en rutas y accesos de&nbsp;Mendoza.<\/p>\n<p style=\"font-weight: 400\">Entre los consejos a tener en cuenta, las autoridades aconsejan manejar con precauci&oacute;n a una velocidad prudente, manteniendo la distancia con otros veh&iacute;culos y respetando las se&ntilde;ales de tr&aacute;nsito.<\/p>\n<p style=\"font-weight: 400\">Por otro lado, al manejar, siempre se debe llevar el cintur&oacute;n de seguridad colocado, tanto el conductor como todos los ocupantes del veh&iacute;culo, y evitar circular hablando por tel&eacute;fono celular.<\/p>\n<p style=\"font-weight: 400\">Otro de los cuidados es no sobrepasar a otro autom&oacute;vil en presencia de doble l&iacute;nea amarilla y circular siempre con las luces bajas encendidas.<\/p>\n<p style=\"font-weight: 400\">A estas recomendaciones se suma: controlar el estado de los neum&aacute;ticos, los frenos, el funcionamiento de las luces, la direcci&oacute;n y la parte el&eacute;ctrica del autom&oacute;vil como requisito imprescindible, ya que son componentes que aportan a la seguridad del veh&iacute;culo.<\/p>\n<p style=\"font-weight: 400\">Para finalizar, es fundamental llevar matafuego, gato hidr&aacute;ulico y balizas y revisar el estado de los cinturones de seguridad, el perfecto funcionamiento de los <em>airbags<\/em>, los espejos retrovisores, limpiaparabrisas y los niveles de combustible y de aceite.<\/p>\n<p>&nbsp;<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Seguridad brinda recomendaciones para prevenir accidentes viales con la presencia de esa contingencia clim&aacute;tica. Ante el pron&oacute;stico de posibles lluvias que pueden registrarse en algunas zonas de la provincia, el Ministerio de Seguridad brinda una serie de recomendaciones para que conductores de veh&iacute;culos no sufran accidentes en rutas y accesos de&nbsp;Mendoza. Entre los consejos a&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/cuidados-a-la-hora-de-manejar-en-dias-de-lluvias\/\"><\/a>","protected":false},"author":77,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/151172"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=151172"}],"version-history":[{"count":3,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/151172\/revisions"}],"predecessor-version":[{"id":151180,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/151172\/revisions\/151180"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=151172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=151172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=151172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}