{"id":154952,"date":"2018-10-05T14:46:32","date_gmt":"2018-10-05T17:46:32","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=154952"},"modified":"2018-10-05T14:46:32","modified_gmt":"2018-10-05T17:46:32","slug":"seguridad-afectara-a-500-policias-para-el-partido-de-river-por-la-copa-total-argentina","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/seguridad-afectara-a-500-policias-para-el-partido-de-river-por-la-copa-total-argentina\/","title":{"rendered":"Seguridad afectar\u00e1 a  500 Polic\u00edas para el partido de River por la Copa Total Argentina"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><h4>El encuentro futbol&iacute;stico comenzar&aacute; a las 15.30, mientras que el de Independiente Rivadavia, en el Gargantini, se confirm&oacute; para la hora 17.<\/h4>\n<p>Este domingo, los equipos de River Plate y Sarmiento, de Resistencia , Chaco, jugar&aacute;n en el Estadio Malvinas Argentinas &nbsp;el partido correspondiente a los cuartos de final de la Copa Total Argentina.<\/p>\n<p>Para el operativo de Seguridad, las autoridades del Gobierno provincial han dispuesto que cerca de 500 polic&iacute;as sean los que custodien tanto el interior del estadio como los alrededores del Parque General San Mart&iacute;n y el centro mendocino.<\/p>\n<p>En los ingresos al estadio habr&aacute;n puestos de seguridad&nbsp; con un estricto control por parte de efectivos de la Polic&iacute;a de la provincia y tambi&eacute;n del Gobierno nacional, bajo el sistema de Tribuna Segura.<\/p>\n<p>El encuentro futbol&iacute;stico comenzar&aacute; a las 15.30 y tendr&aacute; ambos p&uacute;blicos como espectadores, quienes deber&aacute;n ingresar al estadio con la entrada y el documento de identidad.<\/p>\n<p>Los simpatizantes del <em>millo <\/em>se ubicar&aacute;n en la popular sur del Malvinas Argentinas, platea descubierta en su totalidad y la parte suroeste de la platea cubierta.<\/p>\n<p>Mientras que los hinchas del Club Sarmiento de Resistencia Chaco disfrutar&aacute;n del encuentro futbol&iacute;stico desde la popular Norte y platea cubierta sector Norte.<\/p>\n<p>En tanto, ese mismo d&iacute;a, cerca de 100 efectivos policiales ser&aacute;n los encargados de brindar seguridad en el Parque cuando Independiente Rivadavia reciba a Villa D&aacute;lmine en el Estadio Juan Bautista Gargantini, en el marco del campeonato de la Primera B Nacional. Dicho encuentro comenzar&aacute; a las 17.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"El encuentro futbol&iacute;stico comenzar&aacute; a las 15.30, mientras que el de Independiente Rivadavia, en el Gargantini, se confirm&oacute; para la hora 17. Este domingo, los equipos de River Plate y Sarmiento, de Resistencia , Chaco, jugar&aacute;n en el Estadio Malvinas Argentinas &nbsp;el partido correspondiente a los cuartos de final de la Copa Total Argentina. Para&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/seguridad-afectara-a-500-policias-para-el-partido-de-river-por-la-copa-total-argentina\/\"><\/a>","protected":false},"author":63,"featured_media":134014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/154952"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=154952"}],"version-history":[{"count":1,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/154952\/revisions"}],"predecessor-version":[{"id":154953,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/154952\/revisions\/154953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/134014"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=154952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=154952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=154952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}