{"id":156157,"date":"2018-10-12T13:32:17","date_gmt":"2018-10-12T16:32:17","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=156157"},"modified":"2018-10-12T13:32:17","modified_gmt":"2018-10-12T16:32:17","slug":"recomendaciones-viales-para-el-fin-de-semana-largo","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/recomendaciones-viales-para-el-fin-de-semana-largo\/","title":{"rendered":"Recomendaciones viales para el fin de semana largo"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p style=\"font-weight: 400\"><strong>El Ministerio de Seguridad aconseja el uso del cintur&oacute;n y no exceder las velocidades permitidas.<\/strong><\/p>\n<p style=\"font-weight: 400\">En el marco del fin de semana largo que se avecina, el&nbsp;Ministerio de Seguridad, brinda una serie de recomendaciones para prevenir accidentes viales en las rutas o principales accesos en la provincia.<\/p>\n<p style=\"font-weight: 400\">Entre las principales medidas de prevenci&oacute;n se aconseja a los automovilistas usar siempre el cintur&oacute;n de seguridad al momento de conducir en un veh&iacute;culo, evitar manejar si se ha ingerido bebidas alcoh&oacute;licas y respetar las velocidades m&aacute;ximas y m&iacute;nimas.&nbsp;&nbsp;A su vez, es importante evitar el uso del tel&eacute;fono celular&nbsp;&nbsp;ya que este elemento provoca distracciones.<\/p>\n<p style=\"font-weight: 400\">Por otro lado, los ni&ntilde;os menores de 12 a&ntilde;os deber&aacute;n ir sentados atr&aacute;s con el cintur&oacute;n de seguridad colocado, mientras que&nbsp;&nbsp;los peque&ntilde;os de&nbsp;&nbsp;0 a&nbsp;4 a&ntilde;os deber&aacute;n circular en una sillita de seguridad especial.<\/p>\n<p style=\"font-weight: 400\">Tambi&eacute;n es fundamental para&nbsp;&nbsp;prevenir cualquier tipo de accidente llevar siempre en el interior del veh&iacute;culo un kit de seguridad integrado por: un matafuego, un par de balizas, el chaleco reflectivo y un botiqu&iacute;n de primeros auxilios.<\/p>\n<p style=\"font-weight: 400\">Para los motociclistas y ciclistas, es vital el uso del&nbsp;&nbsp;casco y al igual que los automovilistas se debe&nbsp;&nbsp;respetar las se&ntilde;alizaciones como las velocidades permitidas.<\/p>\n<p style=\"font-weight: 400\">Por &uacute;ltimo, para que los peatones no sufran accidentes deber&aacute;n evitar cruzar la calle usando el tel&eacute;fono celular y siempre hacerlo por la&nbsp;&nbsp;senda peatonal.<\/p>\n\n        <style type='text\/css'>\n            #gallery-1 {\n                margin: auto;\n            }\n            #gallery-1 .gallery-item {\n                float: left;\n                margin-top: 10px;\n\n                width: auto;}\n            #gallery-1 img {\n                border: 0px none;\n            }\n            #gallery-1 .gallery-caption {\n                margin-left: 0;\n            }\n        <\/style>\n<script>\njQuery(document).ready(function($) {\n  jQuery('div.gallery-item').hover(function(){\n     \/\/jQuery(this).fadeIn().siblings(':not(.modal)').fadeTo( 'slow' , 0.2);\n     jQuery(this).siblings(':not(.modal)').fadeTo( 'fast' , 0.2);\n     jQuery(this).fadeTo( 'slow' , 1);\n  },function(){\n     \/\/$(this).siblings().andSelf().fadeTo( 'slow' , 1);\n  });\n  jQuery('#gallery-1').on('mouseleave',function(){\n    jQuery('div.gallery-item').fadeTo( 'fast' , 1);\n  })\n});\n<\/script>\n        <!-- see gallery_shortcode() in wp-includes\/media.php -->\n        <h3>GALERIA<\/h3>\n        <div id='gallery-1' class='gallery galleryid-156157'><div class='gallery-item' data-toggle='modal' data-target='#156158' id='r156158'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/caminos-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"156158\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a href='https:\/\/www.mendoza.gov.ar\/prensa\/recomendaciones-viales-para-el-fin-de-semana-largo\/caminos-6\/'><img width=\"700\" height=\"482\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/caminos-700x482.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/caminos.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/caminos-250x172.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/caminos-120x83.jpg 120w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#156158\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div>\n            <br style='clear: both;' \/>\n        <\/div>\n\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"El Ministerio de Seguridad aconseja el uso del cintur&oacute;n y no exceder las velocidades permitidas. En el marco del fin de semana largo que se avecina, el&nbsp;Ministerio de Seguridad, brinda una serie de recomendaciones para prevenir accidentes viales en las rutas o principales accesos en la provincia. Entre las principales medidas de prevenci&oacute;n se aconseja&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/recomendaciones-viales-para-el-fin-de-semana-largo\/\"><\/a>","protected":false},"author":77,"featured_media":156158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/156157"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=156157"}],"version-history":[{"count":1,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/156157\/revisions"}],"predecessor-version":[{"id":156159,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/156157\/revisions\/156159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/156158"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=156157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=156157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=156157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}