{"id":157137,"date":"2018-10-18T16:00:13","date_gmt":"2018-10-18T19:00:13","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=157137"},"modified":"2018-10-18T18:29:55","modified_gmt":"2018-10-18T21:29:55","slug":"la-violencia-de-genero-es-una-pandemia-no-un-delito","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/la-violencia-de-genero-es-una-pandemia-no-un-delito\/","title":{"rendered":"&#8220;La violencia de g\u00e9nero es una pandemia, no un delito&#8221;"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><h5>As&iacute; lo define la Organizaci&oacute;n Mundial de la Salud y lo explic&oacute; la responsable de la unidad especializada, Rosana Dottori, en el Congreso Internacional de Seguridad que tuvo lugar en el Hotel Intercontinental.<\/h5>\n<p>Una de las conferencias que tuvo mayor cantidad de audiencia fue la gir&oacute; sobre el tema Violencia de g&eacute;nero, intervenci&oacute;n en crisis, a cargo de N&eacute;stor Majul, Rosana Dottori y M&oacute;nica Fern&aacute;ndez Poblet.<\/p>\n<p>Rosana Dottori, directora del &aacute;rea de enlace de la unidad especializada en violencia de g&eacute;nero, explic&oacute; que &ldquo;a partir de la creaci&oacute;n de la Ley 8931, sancionada en diciembre de 2016 y que refiere al Sistema Georreferencial de Monitoreo, Supervisi&oacute;n, Rastreo y Alerta Electr&oacute;nico para las mujeres que hayan formalizado denuncia penal por violencia contra la mujer y que cuenten con una medida judicial de prohibici&oacute;n de acercamiento incumplida por el agresor; se transit&oacute; una reestructuraci&oacute;n del Ministerio P&uacute;blico Fiscal y que fue darle forma a las Unidades Fiscales. En este momento tenemos dos Unidades Fiscales de Violencia de G&eacute;nero, una en la Primera Circunscripci&oacute;n Judicial, que comprende al 60% de la poblaci&oacute;n de Mendoza y el 70% de la tramitaci&oacute;n de causas sobre este tema. Por otro lado, en San Rafael, la otra que es en la Segunda Circunscripci&oacute;n, en el resto de las Circunscripciones Valle de Uco y Este, hay Secretar&iacute;as de Violencia dentro de las Unidades Fiscales&rdquo;.<\/p>\n<p>La funcionaria sostuvo: &ldquo;La violencia de g&eacute;nero no es un delito, es un flagelo, una pandemia, as&iacute; la<span class=\"Apple-converted-space\">&nbsp;<\/span>categoriza la Organizaci&oacute;n Mundial de la Salud y est&aacute; tratada dentro de la salud p&uacute;blica, pero que es un tema de seguridad.<\/p>\n<p>&ldquo;Esta ley permite establecer distintas medidas de protecci&oacute;n y fue una decisi&oacute;n pol&iacute;tica lograr y construir un sistema que ponga en valor la decisi&oacute;n de un juez que ha dictado una medida de protecci&oacute;n y que se desoy&oacute; por quien ten&iacute;a la obligaci&oacute;n de cumplirla. Desde que comenz&oacute; el programa se han colocado 79 pares de pulseras de georreferencia&rdquo;.<\/p>\n<p>Respecto de los sistemas georrefenciales, indic&oacute; que &ldquo;esta incorporaci&oacute;n impact&oacute; en el C&oacute;digo Procesal Penal y apareci&oacute; una nueva figura en el derecho de las v&iacute;ctimas, como es en el art&iacute;culo 108 bis, que establece para qu&eacute; casos, cu&aacute;les son los objetivos y cu&aacute;les son los presupuestos para la colocaci&oacute;n de estos sistemas de georreferencia&rdquo;.<\/p>\n<p><b>&ldquo;Hacemos hincapi&eacute; en la terapia psicol&oacute;gica tanto para la mujer como para los agresores&rdquo;<\/b><\/p>\n<p>Por su parte, M&oacute;nica Fern&aacute;ndez Poblet, fiscal especializada en violencia de g&eacute;nero, indic&oacute; que &ldquo;la violencia de g&eacute;nero es parte de una desigualdad hist&oacute;rica de poder del hombre hacia las mujeres. Es decir, un trato desigual cultural, social, f&iacute;sico, psicol&oacute;gico, patrimonial y econ&oacute;mico hacia las mujeres, lo que ha llevado necesariamente a tener pol&iacute;ticas internacionales, nacionales y provinciales para tratar de revertir esta situaci&oacute;n.<span class=\"Apple-converted-space\">&nbsp;<\/span><\/p>\n<p>&ldquo;Este tipo de encuentros es una forma de combatir la violencia. Aqu&iacute; se plantean los problemas y se esboza una posible soluci&oacute;n. Otra es la prevenci&oacute;n, donde el Estado argentino, asumiendo compromisos internacionales, ha hecho una campa&ntilde;a muy grande concientizando a la mujer y a la sociedad en general&rdquo;.<\/p>\n<p>Respecto de este cambio, Fern&aacute;ndez Poblet explic&oacute;: &ldquo;Se ha producido un cambio social, ya que antes los testigos no declaraban y hoy s&iacute; lo hacen y hasta muchas veces denuncian los abusos&rdquo;.<\/p>\n<p>Por otra parte, aclar&oacute; que &ldquo;no todo hecho de violencia es delito penal, porque el maltrato, el acoso, la denigraci&oacute;n y otros actos de crueldad, si no est&aacute;n tipificados en el C&oacute;digo Penal, no son considerados un delito. Entonces, es importante saber que ante estas situaciones que no son un delito penal se debe recurrir a los juzgados de Familia para tener una medida de protecci&oacute;n, donde el juez puede aplicar la prohibici&oacute;n de acercamiento hacia la v&iacute;ctima. El incumplimiento de esta medida da lugar a que despu&eacute;s se pueda pedir la aplicaci&oacute;n de monitoreo dual, siempre y cuando se haya cometido el delito penal&rdquo;.<\/p>\n<p>Y agreg&oacute;: &ldquo;Solamente el femicidio y el homicidio transversal son los &uacute;nicos que han sido declarados como tales en el C&oacute;digo Penal argentino. Pero hay otros delitos, que no fueron tipificados como delitos de g&eacute;nero pero son delitos penales: amenazas, abuso sexual, violaci&oacute;n de domicilio, privaci&oacute;n ileg&iacute;tima de la libertad, que son delitos cometidos en un contexto de violencia de g&eacute;nero. Por lo tanto, pedimos al juez de Familia que brinde protecci&oacute;n a la mujer. La medida m&aacute;s utilizada es la exclusi&oacute;n del hogar y la prohibici&oacute;n de acercamiento, que evitan que se produzca el delito, pero tambi&eacute;n hay otras medidas, como la custodia en el domicilio, la restituci&oacute;n del hogar y fijar una cuota alimentaria provisoria, entre otras&rdquo;.<\/p>\n<p>Al finalizar, explic&oacute; la importancia de la terapia psicol&oacute;gica en estos casos, pero no s&oacute;lo de la mujer, &ldquo;que le permite empoderarse y asumir cierta fuerza, sino tambi&eacute;n el tratamiento de los agresores, para que los hombres que est&aacute;n penados por violencia de g&eacute;nero y han introyectado esta idea de que son superiores a la mujer tengan la posibilidad de hacer un tratamiento en el que &nbsp;comprendan que hay otro tipo de masculinidad que no significa que deben ejercer el poder sobre quienes creen son inferiores&rdquo;.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"As&iacute; lo define la Organizaci&oacute;n Mundial de la Salud y lo explic&oacute; la responsable de la unidad especializada, Rosana Dottori, en el Congreso Internacional de Seguridad que tuvo lugar en el Hotel Intercontinental. Una de las conferencias que tuvo mayor cantidad de audiencia fue la gir&oacute; sobre el tema Violencia de g&eacute;nero, intervenci&oacute;n en crisis,&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/la-violencia-de-genero-es-una-pandemia-no-un-delito\/\"><\/a>","protected":false},"author":62,"featured_media":157162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/157137"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=157137"}],"version-history":[{"count":5,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/157137\/revisions"}],"predecessor-version":[{"id":157227,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/157137\/revisions\/157227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/157162"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=157137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=157137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=157137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}