{"id":158265,"date":"2018-10-25T11:11:03","date_gmt":"2018-10-25T14:11:03","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=158265"},"modified":"2018-10-25T14:01:57","modified_gmt":"2018-10-25T17:01:57","slug":"la-feria-del-libro-2018-tuvo-su-lugar-en-las-carceles-mendocinas","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/la-feria-del-libro-2018-tuvo-su-lugar-en-las-carceles-mendocinas\/","title":{"rendered":"La Feria\u00a0del Libro 2018 tuvo su lugar en las c\u00e1rceles mendocinas"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><h5>El tradicional encuentro dedicado a destacar el trabajo de escritores provinciales, nacionales e internacionales se present&oacute; con un ciclo de conciertos que fue presenciado por personas privadas de libertad.<\/h5>\n<p style=\"font-weight: 400\">Internos del Complejo Penitenciario Boulogne Sur Mer participaron en un Ciclo de Conciertos denominados Festival de Confluencias, con la presencia de cantautores mendocinos y artistas de otros pa&iacute;ses.<\/p>\n<p style=\"font-weight: 400\">Este encuentro se realiz&oacute; en el marco de la Feria del Libro, organizada por&nbsp;la Secretar&iacute;a&nbsp;de Cultura y que este a&ntilde;o rindi&oacute; homenaje a la fallecida escritora Liliana Bodoc.<\/p>\n<p style=\"font-weight: 400\">El objetivo principal de esta actividad es que quienes se encuentran alojados en contextos de encierro puedan contar con herramientas m&aacute;s all&aacute; de las estrictamente formales para favorecer su proceso de resociabilizaci&oacute;n.<\/p>\n<p style=\"font-weight: 400\">Desde el Servicio Penitenciario provincial agradecieron la presencia de los artistas y destacaron el trabajo en conjunto que ambas instituciones realizan, para continuar trabajando en acciones conjuntas, que permitan seguir acercando y promocionando distintas actividades culturales en complejos y unidades carcelarias.<\/p>\n<p style=\"font-weight: 400\">Por su parte, los artistas&nbsp;Facundo Jofr&eacute;, Francisca Figueroa, Federico Jaramillo, Gonzalo Del Peral,&nbsp;Camila Mill&aacute;n, Diego Gui&ntilde;az&uacute;, Ezequiel Borra y &nbsp;Jorge Ibarra,&nbsp;coincidieron que la m&uacute;sica debe llegar a todos los sectores de la sociedad&nbsp;y ser un &aacute;mbito de convivencia en la diversidad, reuniendo en s&iacute; misma diferentes voces, credos e ideolog&iacute;as.<\/p>\n<p style=\"font-weight: 400\"><strong>Inclusi&oacute;n laboral durante la feria<\/strong><\/p>\n<p style=\"font-weight: 400\">Durante la realizaci&oacute;n de&nbsp;la Feria&nbsp;del Libro, personas pertenecientes &nbsp;a la cooperativa de trabajo Germinar ofrecieron sus servicios de lavado sustentable de autos en la playa de estacionamiento del Espacio Cultural Julio Le Parc.<\/p>\n<p style=\"font-weight: 400\">Esta cooperativa, impulsada desde el Ministerio de Econom&iacute;a, Infraestructura y Energ&iacute;a, a trav&eacute;s de&nbsp;la Direcci&oacute;n&nbsp;de Innovaci&oacute;n y Desarrollo Sostenible y&nbsp;la Direcci&oacute;n&nbsp;de Promoci&oacute;n del Liberado, agrupa a personas liberadas de los penales de Mendoza, con el objetivo de que puedan emprender o realizar los oficios una vez recuperada su libertad.<\/p>\n<p style=\"font-weight: 400\">En la actualidad, participan alrededor de 20 personas liberadas en cuatro &aacute;reas de trabajo. Un taller de madera y mimbre, un &aacute;rea tiene que ver con el servicio de <em>catering<\/em> y gastronom&iacute;a, una de construcci&oacute;n en general y el servicio de limpieza ecol&oacute;gica de autos, donde se privilegia el cuidado del agua y el medio ambiente.<\/p>\n\n        <style type='text\/css'>\n            #gallery-1 {\n                margin: auto;\n            }\n            #gallery-1 .gallery-item {\n                float: left;\n                margin-top: 10px;\n\n                width: auto;}\n            #gallery-1 img {\n                border: 0px none;\n            }\n            #gallery-1 .gallery-caption {\n                margin-left: 0;\n            }\n        <\/style>\n<script>\njQuery(document).ready(function($) {\n  jQuery('div.gallery-item').hover(function(){\n     \/\/jQuery(this).fadeIn().siblings(':not(.modal)').fadeTo( 'slow' , 0.2);\n     jQuery(this).siblings(':not(.modal)').fadeTo( 'fast' , 0.2);\n     jQuery(this).fadeTo( 'slow' , 1);\n  },function(){\n     \/\/$(this).siblings().andSelf().fadeTo( 'slow' , 1);\n  });\n  jQuery('#gallery-1').on('mouseleave',function(){\n    jQuery('div.gallery-item').fadeTo( 'fast' , 1);\n  })\n});\n<\/script>\n        <!-- see gallery_shortcode() in wp-includes\/media.php -->\n        <h3>GALERIA<\/h3>\n        <div id='gallery-1' class='gallery galleryid-158265'><div class='gallery-item' data-toggle='modal' data-target='#158266' id='r158266'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4538-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"158266\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a href='https:\/\/www.mendoza.gov.ar\/prensa\/la-feria-del-libro-2018-tuvo-su-lugar-en-las-carceles-mendocinas\/ministerio-de-seguridad-encuentro-internacional-de-cantautores\/'><img width=\"700\" height=\"464\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4538-700x464.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4538-700x464.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4538-250x166.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4538-768x509.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4538-120x79.jpg 120w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#158267\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div><div class='gallery-item' data-toggle='modal' data-target='#158267' id='r158267'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4547-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"158267\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#158266\"><i class=\"text-white fa fa-chevron-left fa-4x\"><\/i><\/a><a href='https:\/\/www.mendoza.gov.ar\/prensa\/la-feria-del-libro-2018-tuvo-su-lugar-en-las-carceles-mendocinas\/ministerio-de-seguridad-encuentro-internacional-de-cantautores-2\/'><img width=\"700\" height=\"464\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4547-700x464.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4547-700x464.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4547-250x166.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4547-768x509.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4547-120x79.jpg 120w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#158268\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div><div class='gallery-item' data-toggle='modal' data-target='#158268' id='r158268'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4533-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"158268\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#158267\"><i class=\"text-white fa fa-chevron-left fa-4x\"><\/i><\/a><a href='https:\/\/www.mendoza.gov.ar\/prensa\/la-feria-del-libro-2018-tuvo-su-lugar-en-las-carceles-mendocinas\/ministerio-de-seguridad-encuentro-internacional-de-cantautores-3\/'><img width=\"700\" height=\"464\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4533-700x464.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4533-700x464.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4533-250x166.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4533-768x509.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/10\/FMS_4533-120x79.jpg 120w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#158266\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div>\n            <br style='clear: both;' \/>\n        <\/div>\n\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"El tradicional encuentro dedicado a destacar el trabajo de escritores provinciales, nacionales e internacionales se present&oacute; con un ciclo de conciertos que fue presenciado por personas privadas de libertad. Internos del Complejo Penitenciario Boulogne Sur Mer participaron en un Ciclo de Conciertos denominados Festival de Confluencias, con la presencia de cantautores mendocinos y artistas de&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/la-feria-del-libro-2018-tuvo-su-lugar-en-las-carceles-mendocinas\/\"><\/a>","protected":false},"author":61,"featured_media":158267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/158265"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=158265"}],"version-history":[{"count":3,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/158265\/revisions"}],"predecessor-version":[{"id":158276,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/158265\/revisions\/158276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/158267"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=158265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=158265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=158265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}