{"id":161154,"date":"2018-11-12T15:42:41","date_gmt":"2018-11-12T18:42:41","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=161154"},"modified":"2018-11-12T16:09:37","modified_gmt":"2018-11-12T19:09:37","slug":"patrulla-de-rescate-ya-trabaja-en-la-prevencion-de-los-andinistas-en-el-parque-aconcagua","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/patrulla-de-rescate-ya-trabaja-en-la-prevencion-de-los-andinistas-en-el-parque-aconcagua\/","title":{"rendered":"Patrulla de Rescate ya trabaja en la prevenci\u00f3n de los andinistas en el Parque Aconcagua"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><h5>La base operativa se instal&oacute; en Plaza de Mulas y contar&aacute; con los servicios m&eacute;dicos y de rescate necesarios. Recomendaciones.<\/h5>\n<p>Tras el inicio de la nueva temporada estival del Parque Provincial Aconcagua, la Patrulla de Rescate, dependiente del Ministerio de Seguridad, instal&oacute; su base de operaciones en Plaza de Mulas.<\/p>\n<p>En esta oportunidad y como cada a&ntilde;o, el personal de la Patrulla traslad&oacute; todos los equipos que ser&aacute;n utilizados por los efectivos durante la temporada, contando con la colaboraci&oacute;n del Cuerpo de Aviaci&oacute;n Policial. La base de operaciones contar&aacute; con los servicios m&eacute;dicos y de rescate ante cualquier emergencia.<\/p>\n<p>Antonio Ibaceta, jefe a cargo de la Patrulla, asegur&oacute; que todas las personas que deseen realizar el ascenso al cerro Aconcagua (6.962 msnm) deber&aacute;n saber y tener en cuenta las recomendaciones de los gu&iacute;as para evitar cualquier tipo de accidente.<\/p>\n<p>Entre las actividades que brindar&aacute;n, se destaca la tarea de concientizaci&oacute;n para las personas que deseen realizar el ascenso al cerro, ya sea informando los cuidados como las consecuencias que pueden llevar a tener al realizar dicha pr&aacute;ctica deportiva. Tambi&eacute;n, los cuidados con el&nbsp; medio ambiente, a fin de preservar la higiene en el parque provincial.<\/p>\n<p><strong>Consejos para evitar accidentes<\/strong><\/p>\n<p>Antes de realizar cualquier tipo de ascenso es importante tener en cuenta las siguientes recomendaciones:<\/p>\n<p>&ndash; Consultar las condiciones metereol&oacute;gicas con antelaci&oacute;n y por el plazo de los pr&oacute;ximos 7 d&iacute;as desde el momento del ascenso.<\/p>\n<p>&ndash; Informar al grupo familiar que est&aacute; por realizar un ascenso a un cerro y el tiempo estimado de duraci&oacute;n.<\/p>\n<p>&ndash; Seguir las recomendaciones de los gu&iacute;as.<\/p>\n\n        <style type='text\/css'>\n            #gallery-1 {\n                margin: auto;\n            }\n            #gallery-1 .gallery-item {\n                float: left;\n                margin-top: 10px;\n\n                width: auto;}\n            #gallery-1 img {\n                border: 0px none;\n            }\n            #gallery-1 .gallery-caption {\n                margin-left: 0;\n            }\n        <\/style>\n<script>\njQuery(document).ready(function($) {\n  jQuery('div.gallery-item').hover(function(){\n     \/\/jQuery(this).fadeIn().siblings(':not(.modal)').fadeTo( 'slow' , 0.2);\n     jQuery(this).siblings(':not(.modal)').fadeTo( 'fast' , 0.2);\n     jQuery(this).fadeTo( 'slow' , 1);\n  },function(){\n     \/\/$(this).siblings().andSelf().fadeTo( 'slow' , 1);\n  });\n  jQuery('#gallery-1').on('mouseleave',function(){\n    jQuery('div.gallery-item').fadeTo( 'fast' , 1);\n  })\n});\n<\/script>\n        <!-- see gallery_shortcode() in wp-includes\/media.php -->\n        <h3>GALERIA<\/h3>\n        <div id='gallery-1' class='gallery galleryid-161154'><div class='gallery-item' data-toggle='modal' data-target='#161155' id='r161155'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181110-WA0002-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"161155\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a href='https:\/\/www.mendoza.gov.ar\/prensa\/patrulla-de-rescate-ya-trabaja-en-la-prevencion-de-los-andinistas-en-el-parque-aconcagua\/img-20181110-wa0002\/'><img width=\"700\" height=\"525\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181110-WA0002-700x525.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181110-WA0002-700x525.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181110-WA0002-250x188.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181110-WA0002-768x576.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181110-WA0002-120x90.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181110-WA0002.jpg 1032w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#161156\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div><div class='gallery-item' data-toggle='modal' data-target='#161156' id='r161156'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181107-WA0087-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"161156\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#161155\"><i class=\"text-white fa fa-chevron-left fa-4x\"><\/i><\/a><a href='https:\/\/www.mendoza.gov.ar\/prensa\/patrulla-de-rescate-ya-trabaja-en-la-prevencion-de-los-andinistas-en-el-parque-aconcagua\/img-20181107-wa0087\/'><img width=\"581\" height=\"1032\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181107-WA0087.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181107-WA0087.jpg 581w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181107-WA0087-250x444.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20181107-WA0087-120x213.jpg 120w\" sizes=\"(max-width: 581px) 100vw, 581px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#161157\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div><div class='gallery-item' data-toggle='modal' data-target='#161157' id='r161157'>\n            <dt class='gallery-icon'>\n                <a style='cursor:pointer;'><img width='150' height='150' src='https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20170821-WA0007-150x150.jpg' class='attachment-thumbnail size-thumbnail' alt='' href=''><\/a>\n             <\/dt><\/div><div class=\"modal fade bs-example-modal-lg\" id=\"161157\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"myModalLabel\">\n  <div class=\"modal-dialog modal-lg\" role=\"document\">\n    <div class=\"\">\n      <div class=\"modal-body\" style=\"text-align: center;\"><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#161156\"><i class=\"text-white fa fa-chevron-left fa-4x\"><\/i><\/a><a href='https:\/\/www.mendoza.gov.ar\/prensa\/patrulla-de-rescate-ya-trabaja-en-la-prevencion-de-los-andinistas-en-el-parque-aconcagua\/img-20170821-wa0007\/'><img width=\"700\" height=\"1244\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20170821-WA0007-700x1244.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20170821-WA0007-700x1244.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20170821-WA0007-250x444.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20170821-WA0007-120x213.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2018\/11\/IMG-20170821-WA0007.jpg 720w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><a data-toggle=\"modal\" data-dismiss=\"modal\" data-target=\"#161155\"><i class=\"text-white fa fa-chevron-right fa-4x\"><\/i><\/a><\/div>\n    <\/div>\n  <\/div>\n<\/div>\n            <br style='clear: both;' \/>\n        <\/div>\n\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"La base operativa se instal&oacute; en Plaza de Mulas y contar&aacute; con los servicios m&eacute;dicos y de rescate necesarios. Recomendaciones. Tras el inicio de la nueva temporada estival del Parque Provincial Aconcagua, la Patrulla de Rescate, dependiente del Ministerio de Seguridad, instal&oacute; su base de operaciones en Plaza de Mulas. En esta oportunidad y como&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/patrulla-de-rescate-ya-trabaja-en-la-prevencion-de-los-andinistas-en-el-parque-aconcagua\/\"><\/a>","protected":false},"author":63,"featured_media":161155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/161154"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=161154"}],"version-history":[{"count":3,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/161154\/revisions"}],"predecessor-version":[{"id":161164,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/161154\/revisions\/161164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/161155"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=161154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=161154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=161154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}