{"id":163348,"date":"2018-11-26T14:46:11","date_gmt":"2018-11-26T17:46:11","guid":{"rendered":"http:\/\/prensa.wp1.mendoza.gov.ar\/?p=163348"},"modified":"2018-11-26T16:47:55","modified_gmt":"2018-11-26T19:47:55","slug":"diversion-nocturna-clausuro-16-fiestas-por-la-presencia-de-menores","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/diversion-nocturna-clausuro-16-fiestas-por-la-presencia-de-menores\/","title":{"rendered":"Diversi\u00f3n Nocturna clausur\u00f3 16 fiestas por la presencia de menores"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><h5>Fue el resultado de 8 procedimientos que se realizaron entre de agosto a noviembre.<\/h5>\n<p>Autoridades de la Subdirecci&oacute;n de Control de Eventos y Locales de Esparcimiento, dependiente del Ministerio de Seguridad, clausuraron 16 fiestas en las que se detect&oacute; la presencia de menores sin que existiera autorizaci&oacute;n para ello. Fue en 8 procedimientos que se realizaron entre los meses de agosto y noviembre de 2018.<\/p>\n<p>Desde Diversi&oacute;n Nocturna explicaron que, en estos casos, el organismo ordena el cese de actividad del local y el pago de una multa. En tanto, el Juzgado de Faltas correspondiente eval&uacute;a sancionar a los padres de los menores, seg&uacute;n lo establece la normativa.<\/p>\n<p>Se clausuraron tres fiestas en el Complejo Norte&ntilde;o de Las Heras; una, en el Sal&oacute;n Castro de Luj&aacute;n; una, en el local Nikki; tres, en Puwa, de Guaymall&eacute;n. Adem&aacute;s, se orden&oacute; finalizar un baile no autorizado, tambi&eacute;n en Guaymall&eacute;n; cuatro en el Club Montecaseros de San Mart&iacute;n; uno en el local Monroe de San Rafael y, por &uacute;ltimo, dos en La Martina.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Fue el resultado de 8 procedimientos que se realizaron entre de agosto a noviembre. Autoridades de la Subdirecci&oacute;n de Control de Eventos y Locales de Esparcimiento, dependiente del Ministerio de Seguridad, clausuraron 16 fiestas en las que se detect&oacute; la presencia de menores sin que existiera autorizaci&oacute;n para ello. Fue en 8 procedimientos que se&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/diversion-nocturna-clausuro-16-fiestas-por-la-presencia-de-menores\/\"><\/a>","protected":false},"author":63,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/163348"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=163348"}],"version-history":[{"count":3,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/163348\/revisions"}],"predecessor-version":[{"id":163386,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/163348\/revisions\/163386"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=163348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=163348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=163348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}