{"id":20112,"date":"2014-08-10T11:16:00","date_gmt":"2014-08-10T11:16:00","guid":{"rendered":"http:\/\/prensa.wp2.mendoza.gov.ar\/el-bid-controla-metas-en-la-ejecucion-de-obras-de-irrigacion\/"},"modified":"2014-08-10T11:16:00","modified_gmt":"2014-08-10T11:16:00","slug":"el-bid-controla-metas-en-la-ejecucion-de-obras-de-irrigacion","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/el-bid-controla-metas-en-la-ejecucion-de-obras-de-irrigacion\/","title":{"rendered":"El BID controla metas en la ejecuci\u00f3n de obras de Irrigaci\u00f3n"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p>Funcionarios del Departamento General de Irrigaci&oacute;n se reunieron con Ricardo Quiroga, Rui de Villalobos y Ricardo Vargas del Valle, miembros del Banco Interamericano de Desarrollo (BID), para evaluar el trabajo integral de las obras financiadas por este &uacute;ltimo a trav&eacute;s del Programa&nbsp; de Servicios Agr&iacute;colas Provinciales (PROSAP).&nbsp;<\/p>\n<p>El objetivo principal del encuentro fue reflexionar, analizar y sugerir mejoras en funci&oacute;n de las lecciones aprendidas&nbsp; durante la ejecuci&oacute;n de los proyectos de riego del PROSAP y c&oacute;mo influye esto en las obras que se est&aacute;n realizando o que se desarrollar&aacute;n pr&oacute;ximamente.<\/p>\n<p>As&iacute; mismo, se debati&oacute; como impactar&iacute;a dicho aprendizaje en posibles futuros proyectos de riego, a trav&eacute;s de una nueva operaci&oacute;n de pr&eacute;stamo que financiar&iacute;a el BID.<\/p>\n<p>&ldquo;Nos visitaron del BID para hacer un seguimiento de las actividades que Irrigaci&oacute;n est&aacute; haciendo con el PROSAP, y el objetivo que nos plantean es hacer un balance sobre las lecciones aprendidas en la ejecuci&oacute;n de obras con PROSAP, cu&aacute;les son las recomendaciones y c&oacute;mo seguir a futuro con posibles nuevas obras&rdquo;, detall&oacute; el superintendente de Irrigaci&oacute;n Jos&eacute; Luis Alvarez.<\/p>\n<p>Por su parte,&nbsp;<span style=\"font-size: 13px\">Ricardo Vargas del Valle, Jefe de Proyectos del BID destac&oacute;&nbsp;<\/span>&ldquo;Fue una reuni&oacute;n programada dentro del proceso de evaluaci&oacute;n final de la inversi&oacute;n que realizamos, mediante un pr&eacute;stamo al PROSAP por una suma de 200 millones de d&oacute;lares, de los cuales buena parte lleg&oacute; a Irrigaci&oacute;n para financiar proyectos h&iacute;dricos importantes. Quer&iacute;amos saber qu&eacute; aprendizaje surgi&oacute; de la ejecuci&oacute;n de distintas obras, para formular nuevas operaciones en el futuro para el PROSAP y para Mendoza. Estuvimos discutiendo los factores que explican por qu&eacute; un proyecto es exitoso y cu&aacute;les son los errores a corregir, para mejorar el dise&ntilde;o de nuevas operaciones&rdquo;.<\/p>\n<p>Una de las grandes obras que se encuentran financiadas bajo esta formalidad son las de modernizaci&oacute;n de la Quinta Zona de Riego, por un monto de $300 millones.&nbsp;<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"El encuentro tuvo como objetivo evaluar el avance de obras financiadas por la entidad internacional a trav\u00e9s del PROSAP y establecer futuras metas.  Actualmente financian por $ 300 millones obras de riego en Lavalle. ","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/20112"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=20112"}],"version-history":[{"count":0,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/20112\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=20112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=20112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=20112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}