{"id":20222,"date":"2014-08-01T15:28:00","date_gmt":"2014-08-01T15:28:00","guid":{"rendered":"http:\/\/prensa.wp2.mendoza.gov.ar\/irrigacion-impermeabiliza-canales-en-valle-de-uco\/"},"modified":"2014-08-01T15:28:00","modified_gmt":"2014-08-01T15:28:00","slug":"irrigacion-impermeabiliza-canales-en-valle-de-uco","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/irrigacion-impermeabiliza-canales-en-valle-de-uco\/","title":{"rendered":"Irrigaci\u00f3n impermeabiliza canales en Valle de Uco"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><span style=\"line-height: 1.6em\">El Departamento General de Irrigaci&oacute;n emprendi&oacute; este a&ntilde;o, por primera vez, la modalidad de obras por administraci&oacute;n. Esto quiere decir que Irrigaci&oacute;n financia y acompa&ntilde;a en la direcci&oacute;n t&eacute;cnica obras que son llevadas adelante por las Inspecciones de Cauce. De esta manera, se reducen los costos de realizaci&oacute;n y genera puestos de trabajo en distintas zonas de la Provincia.<\/span><\/p>\n<p>Ese es el caso de los canales Vista Flores, Barranca y La Manga, que pertenecen a la cuenca del r&iacute;o Tunuy&aacute;n Superior.<\/p>\n<p>En el Vista Flores se comenz&oacute; con un trabajo de hormigonado que consta de una extensi&oacute;n de 475 metros. Esto permitir&aacute; una mejor conducci&oacute;n del agua y disminuci&oacute;n de p&eacute;rdidas por infiltraci&oacute;n.<\/p>\n<p>Lisandro Bourguet, inspector de cauce del Canal Vista Flores, se refiri&oacute; a las obras realizadas: &ldquo;Estamos haciendo una secci&oacute;n del canal de 475 metros con intenci&oacute;n de hacer un poco m&aacute;s y ya llevamos un 60% de la obra realizada. Es una obra que nos la financia el DGI. Digamos todo lo que es el movimiento de suelo, nivelaci&oacute;n y dem&aacute;s&rdquo;.<\/p>\n<p>&ldquo;Este convenio con Irrigaci&oacute;n es muy beneficioso para nosotros. Porque devolvemos el dinero en 36 meses y, con el dinero que nosotros hicimos esta obra, ninguna empresa hace ni 100 metros. La obra se comenz&oacute; en la corta de agua, yo creo que vamos bastante bien y es un desaf&iacute;o para las inspecciones. Esta obra nos va a permitir que el agua llegue m&aacute;s r&aacute;pido, est&eacute; m&aacute;s limpia y en gran cantidad&rdquo;, complet&oacute;&nbsp; Bourguet.<\/p>\n<p>En el Canal Barranca y La Manga se realiz&oacute; un bateado de 1.360 metros que permite una mejor distribuci&oacute;n del agua. Esta obra, al igual que la del Vista Flores, se llev&oacute; a cabo por administraci&oacute;n.<\/p>\n<p>Ra&uacute;l Jofr&eacute;, inspector de cauce del Canal Barranca y La Manga, manifest&oacute; en qu&eacute; consistieron las tareas: &ldquo;Se realiz&oacute; un bateado de todo el canal que nos permiti&oacute; que el agua no se escurra. Antes el agua se escurr&iacute;a y no le llegaba a los regantes. Esta obra se ven&iacute;a pidiendo hace cuatro a&ntilde;os. Hoy la pudimos ejecutar a trav&eacute;s del trabajo por administraci&oacute;n y estamos muy conformes&rdquo;.<\/p>\n<p>Marcelo Alonso, subdelegado del Tunuy&aacute;n Superior, explic&oacute; c&oacute;mo fue llevar a cabo estas obras por administraci&oacute;n con las inspecciones de cauce: &ldquo;es fundamental realizarlas por este m&eacute;todo ya que hemos podido desarrollarlas en grandes extensiones y a bajo costo. Estamos m&aacute;s que contentos con la capacitaci&oacute;n que se le dio tanto al personal de la inspecci&oacute;n como a los obreros que trabajaron. La idea es seguir realizando proyectos ya que este m&eacute;todo ha sido muy favorable&rdquo;.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Las obras por administraci\u00f3n se realizan en conjunto con las Inspecciones de Cauce para para modernizar y hormigonar  la red de riego de Mendoza. Los canales Vista Flores, Barranca y La Manga fueron algunos de los beneficiados.","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/20222"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=20222"}],"version-history":[{"count":0,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/20222\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=20222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=20222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=20222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}