{"id":278879,"date":"2021-07-31T07:13:00","date_gmt":"2021-07-31T10:13:00","guid":{"rendered":"https:\/\/www.mendoza.gov.ar\/prensa\/?p=278879"},"modified":"2021-07-30T18:16:13","modified_gmt":"2021-07-30T21:16:13","slug":"se-publicaron-nuevas-licitaciones-para-construccion-de-viviendas","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/se-publicaron-nuevas-licitaciones-para-construccion-de-viviendas\/","title":{"rendered":"Se publicaron nuevas licitaciones para construcci\u00f3n de viviendas"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><h5>En la &uacute;ltima semana, el Instituto Provincial de la Vivienda ha realizado llamados a licitaci&oacute;n y concurso p&uacute;blico para la edificaci&oacute;n de m&aacute;s de 650 casas a trav&eacute;s de diversos programas.<\/h5>\n\n\n\n<p>Con una inversi&oacute;n que supera los $800 millones, el Gobierno Provincial construir&aacute; en los pr&oacute;ximos meses alrededor de 670 viviendas sociales en Mendoza.<\/p>\n\n\n\n<p>Al ya conocido plan provincial Mendoza Construye -l&iacute;neas 1 y 2-, se le suma una nueva l&iacute;nea que proviene de la Naci&oacute;n a trav&eacute;s del Ministerio de Desarrollo Territorial y H&aacute;bitat. Se trata del Programa Nacional Casa Propia-Construir Futuro, que destina fondos para la construcci&oacute;n de viviendas, veredas, forestales y alumbrado p&uacute;blico.<\/p>\n\n\n\n<p>En el marco de este programa, el IPV ha realizado tres llamados a licitaci&oacute;n para 146 viviendas correspondientes a los siguientes emprendimientos: Isla del R&iacute;o Diamante (20 viviendas) de San Rafael; Flores Olivares (24) de Capital; Padre Contreras (14) y Virgen del Rosario (9) de Lavalle; segunda etapa del 4 de Julio (22) de Godoy Cruz; Uni&oacute;n y Progreso II (16) de La Paz; y Brandsen (41) de Rivadavia.<\/p>\n\n\n\n<p>Estas obras tienen un plazo fijado de entre 8 y 10 meses, por lo que podr&iacute;an estar finalizadas a fines del 2022.<\/p>\n\n\n\n<p>Adem&aacute;s de estas viviendas, el IPV convoc&oacute; a concurso p&uacute;blico de proyectos para una nueva etapa del Mendoza Construye l&iacute;nea 2. Se trata de emprendimientos que ser&aacute;n financiados conjuntamente por la Provincia y los desarrolladores cuyas propuestas sean seleccionadas.<\/p>\n\n\n\n<p>La convocatoria abarca unas 500 viviendas que ser&aacute;n destinadas a grupos familiares de ingresos medios, y que cuenten con la posibilidad de realizar un aporte inicial que depender&aacute; de la unidad seleccionada.<\/p>\n\n\n\n<p>Finalmente, otro barrio licitado fue el Aguaribay VI de Jun&iacute;n, de 31 casas, que ser&aacute; construido y financiado con fondos provinciales en el marco de la L&iacute;nea 1 del Plan Mendoza Construye.<\/p>\n\n\n\n<p>Cabe destacar que los pliegos de bases y condiciones ya se encuentran disponibles en la p&aacute;gina web del IPV <a href=\"http:\/\/www.ipvmendoza.gov.ar\">www.ipvmendoza.gov.ar<\/a> y en el portal de Compras de la Provincia.<\/p>\n\n\n\n<p>Las aperturas de sobres se realizar&aacute;n en la sede del IPV de acuerdo a las fechas estipuladas en cada convocatoria.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/07\/Fotos-generales-barrios-IPV-4.jpg\"><img src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/07\/Fotos-generales-barrios-IPV-4-700x466.jpg\" alt=\"\" data-id=\"278881\" data-full-url=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/07\/Fotos-generales-barrios-IPV-4.jpg\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=278881\" class=\"wp-image-278881 img-responsive center-block\"><\/a><\/figure><\/li><\/ul><\/figure>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"En la &uacute;ltima semana, el Instituto Provincial de la Vivienda ha realizado llamados a licitaci&oacute;n y concurso p&uacute;blico para la edificaci&oacute;n de m&aacute;s de 650 casas a trav&eacute;s de diversos programas. Con una inversi&oacute;n que supera los $800 millones, el Gobierno Provincial construir&aacute; en los pr&oacute;ximos meses alrededor de 670 viviendas sociales en Mendoza. Al&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/se-publicaron-nuevas-licitaciones-para-construccion-de-viviendas\/\"><\/a>","protected":false},"author":68,"featured_media":278881,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1801],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/278879"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=278879"}],"version-history":[{"count":2,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/278879\/revisions"}],"predecessor-version":[{"id":278882,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/278879\/revisions\/278882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/278881"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=278879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=278879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=278879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}