{"id":282552,"date":"2021-08-31T13:03:39","date_gmt":"2021-08-31T16:03:39","guid":{"rendered":"https:\/\/www.mendoza.gov.ar\/prensa\/?p=282552"},"modified":"2021-08-31T15:39:50","modified_gmt":"2021-08-31T18:39:50","slug":"avenida-urbana-del-oeste-finalizaron-dos-obras-de-gran-importancia-para-la-traza","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/avenida-urbana-del-oeste-finalizaron-dos-obras-de-gran-importancia-para-la-traza\/","title":{"rendered":"Avenida Urbana del Oeste: finalizaron dos obras de gran importancia para la traza"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><h5>Se trata del montaje de columnas para el levantamiento de la l&iacute;nea de alta tensi&oacute;n y el hormigonado del nuevo puente sobre el canal Maure.<\/h5>\n\n\n\n<p>Los trabajos sobre la Avenida Urbana del Oeste avanzan significativamente y, m&aacute;s all&aacute; de la obra b&aacute;sica, que se encuentra en m&aacute;s de 90% de desarrollo, ya finalizaron dos tareas fundamentales que permiten continuar con la ejecuci&oacute;n de la traza propiamente dicha.<\/p>\n\n\n\n<p>Por una parte, Edemsa incorpor&oacute; nuevas columnas para elevar dos ternas de alta tensi&oacute;n en la zona donde confluye la autov&iacute;a con la calle Illia. Otorgar&aacute;n la altura reglamentaria para que la ruta pase por debajo y evitar problemas de seguridad para el tr&aacute;nsito de veh&iacute;culos mayores. Estos trabajos, que comenzaron en mayo, se pudieron hacer sin necesidad de cortar el suministro.<\/p>\n\n\n\n<p>&ldquo;A partir de la finalizaci&oacute;n de ese trabajo, las m&aacute;quinas pueden retomar las tareas sobre la carpeta asf&aacute;ltica, por lo que a partir de ahora la colocaci&oacute;n del asfalto se har&aacute; de manera continua y a mayor velocidad&rdquo;, explic&oacute; Hugo Hern&aacute;ndez, director de Obras del Ministerio de Planificaci&oacute;n e Infraestructura P&uacute;blica.<\/p>\n\n\n\n<p>Por otro lado, concluyeron los trabajos de hormigonado (llenado de losas y<br>apoyos) para el montaje del nuevo puente sobre el canal Maure, al que solo le resta la colocaci&oacute;n de barandas y de la carpeta asf&aacute;ltica superior.<\/p>\n\n\n\n<p>Esta tarea se suma a otras obras complementarias, como la nueva rotonda<br>emplazada sobre la avenida y la calle Segundo Sombra, que ampliar&aacute; la<br>conectividad y ordenar&aacute; el tr&aacute;nsito de la zona.<\/p>\n\n\n\n<p>Tambi&eacute;n, la empresa mendocina de agua realiz&oacute; importantes trabajos<br>estructurales para corregir desperfectos en las ca&ntilde;er&iacute;as que pasan por debajo de la traza.<\/p>\n\n\n\n<p><strong>Las obras<\/strong><\/p>\n\n\n\n<p>Con el objetivo puesto en descomprimir la circulaci&oacute;n en el Corredor del Oeste y mejorar la conexi&oacute;n entre los departamentos de Godoy Cruz, Luj&aacute;n de Cuyo y Ciudad, las obras se basan en la construcci&oacute;n de una carpeta asf&aacute;ltica con barreras de separaci&oacute;n entre los dos carriles de circulaci&oacute;n que se ejecutan en doble v&iacute;a, defensas met&aacute;licas y aluvionales, cunetas y banquinas, alumbrado LED, seis rotondas y tres puentes.<\/p>\n\n\n\n<p>Planteado en cinco tramos, con diferentes caracter&iacute;sticas desde el punto de vista del desarrollo urbano, el primero de 900 metros de longitud prev&eacute; la apertura de la calle Per&oacute;n desde la Rotonda de Palmares hasta la calle Los Cardos. Las calzadas est&aacute;n divididas con una defensa tipo New Jersey.<\/p>\n\n\n\n<p>El segundo tramo, netamente urbano, est&aacute; delimitado por los barrios La<br>Estanzuela y Puesta del Sol y se extiende desde calle Los Cardos y Lorenzo<br>Soler. El tercero est&aacute; comprendido entre las calles Lorenzo Soler y Einstein. Sobre este sector se deben reubicar las l&iacute;neas el&eacute;ctricas y, adem&aacute;s, se construyen cunetas de hormig&oacute;n.<\/p>\n\n\n\n<p>El cuarto tramo se emplaza entre las calles Einstein y Pedro Goyena, y el quinto, en la calle San Vicente, entre Vistalba y San Francisco de As&iacute;s.<\/p>\n\n\n\n<p>Para un adecuado nivel de servicio, se plantearon obras especiales, como la<br>construcci&oacute;n de tres puentes: sobre el dique Maure, sobre la calle Vistalba y sobre el zanj&oacute;n Fr&iacute;as. Adem&aacute;s, se realizar&aacute; la adecuaci&oacute;n de la rotonda San Vicente-Talcahuano y la ampliaci&oacute;n de calzada en la rotonda sobre la calle San Francisco de As&iacute;s.<\/p>\n\n\n\n<p>Asimismo, a lo largo de la traza se emplazan seis rotondas, en la calle Los Cardos y Avenida Per&oacute;n; la segunda, en la calle Segundo Sombra y la avenida Per&oacute;n; la tercera, sobre las calles Barbados, Gorriti y avenida Per&oacute;n; otra, sobre las calles Vistalba, Gorriti y las avenidas Per&oacute;n y San Vicente; una, en la calle Talcahuano y la avenida San Vicente, y la &uacute;ltima, en las avenidas San Vicente y San Francisco de As&iacute;s.<\/p>\n\n\n\n<p>&ldquo;Es importante destacar que sobre la rotonda de calle Vistalba, Gorriti, Per&oacute;n y San Vicente se empezaron a realizar una serie de trabajos integrados -viales e hidr&aacute;ulicos- de hormigonado y rectificaci&oacute;n de varios tramos en canales como el Gorriti, Vistalba. Ah&iacute; se ha hecho un desv&iacute;o de tr&aacute;nsito para ejecutar las tareas&rdquo;, explic&oacute; Hern&aacute;ndez.<\/p>\n\n\n\n<p>Las obras tienen financiamiento del Fondo Fiduciario Federal de Infraestructura Regional, del Ministerio del Interior de la Naci&oacute;n.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-7-1-700x394.jpg\"><img loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-7-1-700x394.jpg\" alt=\"\" data-id=\"282559\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=282559\" class=\"wp-image-282559 img-responsive center-block\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-7-1-700x394.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-7-1-250x141.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-7-1-768x432.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-7-1-120x68.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-7-1.jpg 1280w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-6-1-700x394.jpg\"><img loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-6-1-700x394.jpg\" alt=\"\" data-id=\"282560\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=282560\" class=\"wp-image-282560 img-responsive center-block\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-6-1-700x394.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-6-1-250x141.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-6-1-768x432.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-6-1-120x68.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-6-1.jpg 1280w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-5-700x394.jpg\"><img loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-5-700x394.jpg\" alt=\"\" data-id=\"282561\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=282561\" class=\"wp-image-282561 img-responsive center-block\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-5-700x394.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-5-250x141.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-5-768x432.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-5-120x68.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-5.jpg 1280w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-4-700x394.jpg\"><img loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-4-700x394.jpg\" alt=\"\" data-id=\"282562\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=282562\" class=\"wp-image-282562 img-responsive center-block\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-4-700x394.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-4-250x141.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-4-768x432.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-4-120x68.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-4.jpg 1280w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-1-700x394.jpg\"><img loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-1-700x394.jpg\" alt=\"\" data-id=\"282563\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=282563\" class=\"wp-image-282563 img-responsive center-block\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-1-700x394.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-1-250x141.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-1-768x432.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-1-120x68.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-1.jpg 1280w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-2-700x394.jpg\"><img loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-2-700x394.jpg\" alt=\"\" data-id=\"282564\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=282564\" class=\"wp-image-282564 img-responsive center-block\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-2-700x394.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-2-250x141.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-2-768x432.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-2-120x68.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-2.jpg 1280w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-3-700x394.jpg\"><img loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-3-700x394.jpg\" alt=\"\" data-id=\"282565\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=282565\" class=\"wp-image-282565 img-responsive center-block\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-3-700x394.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-3-250x141.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-3-768x432.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-3-120x68.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-3.jpg 1280w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-8-700x525.jpg\"><img loading=\"lazy\" width=\"700\" height=\"525\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-8-700x525.jpg\" alt=\"\" data-id=\"282566\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=282566\" class=\"wp-image-282566 img-responsive center-block\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-8-700x525.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-8-250x188.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-8-768x576.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-8-1536x1152.jpg 1536w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-8-120x90.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-8.jpg 1600w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-9.jpg\"><img loading=\"lazy\" width=\"700\" height=\"394\" src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-9-700x394.jpg\" alt=\"\" data-id=\"282567\" data-full-url=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-9.jpg\" data-link=\"https:\/\/www.mendoza.gov.ar\/prensa\/?attachment_id=282567\" class=\"wp-image-282567 img-responsive center-block\" srcset=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-9-700x394.jpg 700w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-9-250x141.jpg 250w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-9-768x432.jpg 768w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-9-120x68.jpg 120w, https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/08\/Avenida-Urbana-del-Oeste-9.jpg 1280w\" sizes=\"(max-width: 700px) 100vw, 700px\"><\/a><\/figure><\/li><\/ul><\/figure>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Se trata del montaje de columnas para el levantamiento de la l&iacute;nea de alta tensi&oacute;n y el hormigonado del nuevo puente sobre el canal Maure. Los trabajos sobre la Avenida Urbana del Oeste avanzan significativamente y, m&aacute;s all&aacute; de la obra b&aacute;sica, que se encuentra en m&aacute;s de 90% de desarrollo, ya finalizaron dos tareas&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/avenida-urbana-del-oeste-finalizaron-dos-obras-de-gran-importancia-para-la-traza\/\"><\/a>","protected":false},"author":61,"featured_media":282567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1801],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/282552"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=282552"}],"version-history":[{"count":3,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/282552\/revisions"}],"predecessor-version":[{"id":282597,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/282552\/revisions\/282597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/282567"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=282552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=282552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=282552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}