{"id":291258,"date":"2021-11-03T09:12:39","date_gmt":"2021-11-03T12:12:39","guid":{"rendered":"https:\/\/www.mendoza.gov.ar\/prensa\/?p=291258"},"modified":"2021-11-03T13:50:06","modified_gmt":"2021-11-03T16:50:06","slug":"mendoza-gano-un-premio-y-obtendra-3-500-vacunas-para-combatir-la-hidatidosis-en-ganado-ovino-y-caprino","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/mendoza-gano-un-premio-y-obtendra-3-500-vacunas-para-combatir-la-hidatidosis-en-ganado-ovino-y-caprino\/","title":{"rendered":"Mendoza gan\u00f3 un premio de 3.500 vacunas para combatir la hidatidosis en ganado ovino y caprino"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><h5><strong>Se trata de una enfermedad zoon&oacute;tica de la que se detectan unos 35 casos al a&ntilde;o en la provincia. No es grave para el animal, pero al transmitirse a los humanos genera diversas complicaciones en la salud. El proyecto ganador fue impulsado por la Direcci&oacute;n de Ganader&iacute;a en conjunto con el Senasa y la Fundaci&oacute;n Coprosamen.<\/strong><\/h5>\n\n\n\n<p>Mendoza gan&oacute; el primer premio del concurso nacional &ldquo;Adri&aacute;n Bitsch&rdquo;, de Laboratorios Tecnovax, y obtendr&aacute; 3.500 vacunas para combatir la hidatidosis en ganado ovino y caprino. La enfermedad es zoon&oacute;tica, por lo que se puede transmitir a los humanos a trav&eacute;s de la oveja, la cabra o las mascotas y generar complicaciones de consideraci&oacute;n en la salud de las personas que se desempe&ntilde;an en este sector productivo. &nbsp;<\/p>\n\n\n\n<p>Seg&uacute;n detallaron desde la cartera econ&oacute;mica provincial, la iniciativa fue impulsada por Pablo Dri (ingeniero zootecnista), de la Direcci&oacute;n de Ganader&iacute;a de Mendoza, en conjunto con los m&eacute;dicos veterinarios Sergio Rivero y Pablo Miralles, del Servicio Nacional de Sanidad y Calidad Agroalimentaria (Senasa), y el m&eacute;dico veterinario Federico Vally, de la Fundaci&oacute;n Comisi&oacute;n Provincial de Sanidad Animal Mendoza (Coprosamen).&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Pablo Dri, coordinador de planes caprinos y ovinos de la Direcci&oacute;n de Ganader&iacute;a de la provincia, coment&oacute; que el concurso tuvo como fecha l&iacute;mite el mes de julio y recientemente fueron notificados de ser los ganadores del primer premio por el proyecto presentado que llev&oacute; por nombre &ldquo;Prevenci&oacute;n de la hidatidosis&rdquo;, un escrito que deb&iacute;a presentarse en no m&aacute;s de 4.000 palabras y que incluyera un plan de control de la enfermedad, sumando la vacunaci&oacute;n de hospederos intermediarios. &nbsp;<\/p>\n\n\n\n<p>Sobre este &uacute;ltimo punto, Dri coment&oacute; que la zona a abarcar es la localidad de El Sosneado, en San Rafael: &ldquo;All&iacute; es donde se encuentra cerca de 50% de los animales y estamos trabajando en nuevos proyectos que nos permitan llegar a la totalidad de los ovinos y caprinos de la provincia. La combinaci&oacute;n de tener perros como mascotas que, a la vez, colaboran con el trabajo diario, m&aacute;s la faena para consumo y el destino de las v&iacute;sceras de esos animales para los perros, ha hecho que esta enfermedad se mantenga. En el caso de Mendoza, es la segunda en importancia luego del mal de Chagas, y en tercer lugar se encuentra las brucelosis&rdquo;, destac&oacute; Dri. &nbsp;<\/p>\n\n\n\n<p>Seg&uacute;n detall&oacute;, la enfermedad se ha mantenido controlada gracias al trabajo constante mediante campa&ntilde;as de concientizaci&oacute;n y, a la vez, impulsando operativos de desparasitado de perros mediante el suministro de comprimidos a trav&eacute;s del Ministerio de Salud de la provincia. &nbsp;<\/p>\n\n\n\n<p>La hidatidosis es una enfermedad parasitaria grave que se transmite de los animales al hombre. Causa la aparici&oacute;n de quistes hidat&iacute;dicos que representan una seria amenaza para la vida de las personas infectadas. La enfermedad es causada por cestodos del g&eacute;nero <em>Echinococcus granulosu<\/em>s, que eliminan los animales carn&iacute;voros en su materia fecal y por medio de esta contagian a hu&eacute;spedes accidentales, entre los que se encuentran los animales herb&iacute;voros y el ser humano. &nbsp;<\/p>\n\n\n\n<p>Es la zoonosis (enfermedad que se transmite de los animales al hombre) con mayor prevalencia en Argentina y tiene una distribuci&oacute;n end&eacute;mica e hiperend&eacute;mica a nivel mundial. La diseminaci&oacute;n en humanos est&aacute; fuertemente influida por la convivencia del ser humano, los perros y el ganado. &nbsp;<\/p>\n\n\n\n<p>El ciclo biol&oacute;gico de la hidatidosis comienza cuando un carn&iacute;voro, generalmente canino, ingiere v&iacute;sceras enfermas de un hospedero intermediario herb&iacute;voro como oveja, cabra, vaca o cerdo. El perro infectado elimina por materia fecal miles de huevos embrionados que contaminan el medioambiente por hasta 41 meses manteniendo vivo el ciclo biol&oacute;gico de la hidatidosis y enfermando nuevamente a los herb&iacute;voros. &nbsp;<\/p>\n\n\n\n<p>El ser humano es un hospedero accidental, que se infecta al ingerir huevos viables por contacto directo con los caninos o por medio de la ingesta del agua, verduras o frutas contaminadas por la materia fecal de estos. Los ni&ntilde;os peque&ntilde;os representan el grupo m&aacute;s susceptible de contagio de hidatidosis, por el estrecho v&iacute;nculo que guardan con los caninos y el medioambiente.<\/p>\n\n\n\n<p>&ldquo;Este tipo de convivencia es muy com&uacute;n en el secano mendocino, b&aacute;sicamente en el suroeste de Mendoza y en el norte lavallino. Vamos a provechar para tratar de que a futuro se pueda afrontar un plan anual que permita ir disminuyendo el impacto de esta enfermedad y, por qu&eacute; no, intentar erradicarla a pesar de que sea algo muy complejo&rdquo;, cerr&oacute; el Ingeniero. &nbsp;<\/p>\n\n\n\n<p><strong>Sobre Bitsch &nbsp;<\/strong><\/p>\n\n\n\n<p>El concurso nacional llev&oacute; el nombre de Adri&aacute;n Bitsch, quien fue un m&eacute;dico veterinario oriundo de Tierra del Fuego. Fue uno de los referentes de Argentina en hidatidosis y producci&oacute;n ovina. Fue comunicador, investigador y profesor. Falleci&oacute; en 2011. &nbsp;<\/p>\n\n\n\n<p><strong>Tecnovax &nbsp;<\/strong><\/p>\n\n\n\n<p>Es una empresa biofarmac&eacute;utica dedicada al desarrollo y producci&oacute;n de biol&oacute;gicos para la prevenci&oacute;n de enfermedades que afectan la sanidad animal. El laboratorio fue fundado en 2003 y es reconocido por la calidad y seguridad de sus productos, los que exporta desde sus dos plantas de Argentina a 15 pa&iacute;ses del mundo. Actualmente dispone de tres unidades de negocios en las &aacute;reas de vacunas para ganader&iacute;a, peque&ntilde;os animales y salm&oacute;nidos. En 2006, el laboratorio fue certificado bajo el sistema de gesti&oacute;n de la calidad ISO 9001:2000. En 2010 present&oacute; al mercado la primera vacuna del mundo contra hidatidosis, la principal zoonosis de Argentina. &nbsp;<\/p>\n\n\n\n<p>El laboratorio actualmente cuenta con filiales en Chile, Brasil y Uruguay y posee representantes comerciales en Argentina, Colombia, Chile, Per&uacute;, Paraguay, Bolivia, Brasil, Jordania, Arabia Saudita, Siria, Sud&aacute;frica, L&iacute;bano, Sud&aacute;n, Egipto, Om&aacute;n, Emiratos &Aacute;rabes Unidos y Uruguay, entre otros.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img src=\"https:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/5\/2021\/11\/ovejas-700x467.jpg\" alt=\"\" class=\"wp-image-291259 img-responsive center-block\"><\/figure>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Se trata de una enfermedad zoon&oacute;tica de la que se detectan unos 35 casos al a&ntilde;o en la provincia. No es grave para el animal, pero al transmitirse a los humanos genera diversas complicaciones en la salud. El proyecto ganador fue impulsado por la Direcci&oacute;n de Ganader&iacute;a en conjunto con el Senasa y la Fundaci&oacute;n&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/mendoza-gano-un-premio-y-obtendra-3-500-vacunas-para-combatir-la-hidatidosis-en-ganado-ovino-y-caprino\/\"><\/a>","protected":false},"author":62,"featured_media":291259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/291258"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=291258"}],"version-history":[{"count":9,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/291258\/revisions"}],"predecessor-version":[{"id":291327,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/291258\/revisions\/291327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/291259"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=291258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=291258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=291258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}