{"id":3407,"date":"2014-06-20T13:10:00","date_gmt":"2014-06-20T13:10:00","guid":{"rendered":"http:\/\/prensa.wp2.mendoza.gov.ar\/?p=3407"},"modified":"2014-06-20T13:10:00","modified_gmt":"2014-06-20T13:10:00","slug":"salud-recuerda-la-colocacion-de-la-vacunacion-contra-la-gripe-para-los-grupos-de-riesgo","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/salud-recuerda-la-colocacion-de-la-vacunacion-contra-la-gripe-para-los-grupos-de-riesgo\/","title":{"rendered":"Salud recuerda la colocaci\u00f3n de la vacunaci\u00f3n contra la gripe para los grupos de riesgo"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><img src=\"https:\/\/www.mendoza.gov.ar\/prensa\/wp-content\/uploads\/sites\/23\/2014\/08\/view_crop_15607.JPG\" class=\" img-responsive center-block\"><\/p>\n<p>El Ministerio de Salud inst&oacute; a la poblaci&oacute;n a sostener la estrategia de vacunaci&oacute;n antigripal, que en los &uacute;ltimos a&ntilde;os permiti&oacute; reducir sensiblemente el impacto de esta patolog&iacute;a, al convocar a las personas comprendidas en los grupos de riesgo. Para su colocaci&oacute;n se deber&aacute;&nbsp;concurrir al Vacunatorio Central y los centros de salud p&uacute;blica para recibir la vacuna en forma gratuita y obligatoria.<\/p>\n<p>Desde la cartera sanitaria nacional, destacaron que a la fecha, se ha notificado la aplicaci&oacute;n de casi 4&nbsp;millones de dosis dentro de los grupos de riesgo, raz&oacute;n por la cual la cobertura global est&aacute; alcanzando el 50% de la poblaci&oacute;n objetivo.<\/p>\n<p>El inicio del invierno y el descenso de las temperaturas son el escenario propicio para el incremento de las enfermedades respiratorias, por lo que todos aquellos que tienen indicada por un m&eacute;dico la vacuna y aun no se la aplicaron, deben hacerlo lo antes posible.<\/p>\n<p>La vacuna est&aacute; destinada al personal de salud, embarazadas, pu&eacute;rperas hasta los 6 meses, ni&ntilde;os de 6 a 24 meses, personas entre 2 a 64 a&ntilde;os que presenten enfermedades cr&oacute;nicas y los adultos mayores de 65 a&ntilde;os.<\/p>\n<p>Para esto, el Ministerio de Salud de la Naci&oacute;n adquiri&oacute; para el a&ntilde;o 2014 nueve millones de dosis de vacunas, que son gratuitas y obligatorias para las personas que presentan mayor riesgo de fallecer por esta enfermedad. Las dosis contin&uacute;an distribuy&eacute;ndose en forma sostenida entre los vacunatorios y hospitales p&uacute;blicos de todo el pa&iacute;s.<\/p>\n<p>La jefa del Programa de Inmunizaciones de Mendoza, Iris Aguilar, destac&oacute; que \"se han aplicado m&aacute;s de 100&nbsp;mil dosis de la vacuna antigripal&rdquo;, al tiempo que se&ntilde;al&oacute; que &ldquo;con la vacuna se busca proteger a la poblaci&oacute;n con mayor riesgo de tener complicaciones y morir&rdquo;.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"El Ministerio de Salud inst&oacute; a la poblaci&oacute;n a sostener la estrategia de vacunaci&oacute;n antigripal, que en los &uacute;ltimos a&ntilde;os permiti&oacute; reducir sensiblemente el impacto de esta patolog&iacute;a, al convocar a las personas comprendidas en los grupos de riesgo. Para su colocaci&oacute;n se deber&aacute;&nbsp;concurrir al Vacunatorio Central y los centros de salud p&uacute;blica para recibir&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/salud-recuerda-la-colocacion-de-la-vacunacion-contra-la-gripe-para-los-grupos-de-riesgo\/\"><\/a>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/3407"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=3407"}],"version-history":[{"count":0,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/3407\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=3407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=3407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=3407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}