{"id":3530,"date":"2014-06-27T12:20:00","date_gmt":"2014-06-27T12:20:00","guid":{"rendered":"http:\/\/prensa.wp2.mendoza.gov.ar\/?p=3530"},"modified":"2014-06-27T12:20:00","modified_gmt":"2014-06-27T12:20:00","slug":"el-hospital-lencinas-incorpora-servicio-de-sexologia-gratuito-a-la-comunidad","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/el-hospital-lencinas-incorpora-servicio-de-sexologia-gratuito-a-la-comunidad\/","title":{"rendered":"El Hospital Lencinas incorpora servicio de sexolog\u00eda gratuito a la comunidad"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p>El Ministerio de Salud&nbsp;contin&uacute;a trabajando para lograr mayor accesibilidad y equidad&nbsp; en las prestaciones sanitarias, en esta oportunidad el hospital N&eacute;stor Lencinas, suma un nuevo&nbsp; servicio de sexolog&iacute;a para hombres y mujeres.<\/p>\n<p>El mismo est&aacute; a cargo del Dr. Edgardo Pr&iacute;ncipi, especialista en urolog&iacute;a y&nbsp;abordar&aacute; enfermedades de transmisi&oacute;n sexual (ETS), Alteraciones del deseo sexual y orgasmo, entre otras.<\/p>\n<p>En el Hospital se realizan estudios como:<\/p>\n<ul>\n<li>Penescopias: Para control de&nbsp;Enfermedades de Transmisi&oacute;n Sexual.<\/li>\n<li>Bioestesiometr&iacute;a: Para eyaculaci&oacute;n precoz.<\/li>\n<li>Test vascular con drogas vasoactivas: Para Disfunci&oacute;n Sexual Er&eacute;ctil.<\/li>\n<li>Doppler peneano: Para&nbsp;Disfunci&oacute;n Sexual Er&eacute;ctil.<\/li>\n<li>Tratamiento con electro bistur&iacute; de condilomas y verrugas genitales.<\/li>\n<li>Terapia sexol&oacute;gica para eyaculaci&oacute;n precoz, disfunci&oacute;n sexual er&eacute;ctil y alteraci&oacute;n del deseo sexual.<\/li>\n<li>Estudios con drogas vasoactivas para enfermedad de Peyronie (curvatura peneana).<\/li>\n<li>Control cl&iacute;nico del perfil hormonal y factores de riesgo.<\/li>\n<\/ul>\n<p>A esto se le agrega la consulta urol&oacute;gica y ginecol&oacute;gica que el paciente requiera.<\/p>\n<p>Quienes deseen realizar consultas, deben pedir turnos v&iacute;a telef&oacute;nica en el 0800 800 7258 de lunes a viernes de 9 a 19 hs.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"El Ministerio de Salud&nbsp;contin&uacute;a trabajando para lograr mayor accesibilidad y equidad&nbsp; en las prestaciones sanitarias, en esta oportunidad el hospital N&eacute;stor Lencinas, suma un nuevo&nbsp; servicio de sexolog&iacute;a para hombres y mujeres. El mismo est&aacute; a cargo del Dr. Edgardo Pr&iacute;ncipi, especialista en urolog&iacute;a y&nbsp;abordar&aacute; enfermedades de transmisi&oacute;n sexual (ETS), Alteraciones del deseo sexual y&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/el-hospital-lencinas-incorpora-servicio-de-sexologia-gratuito-a-la-comunidad\/\"><\/a>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[32],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/3530"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=3530"}],"version-history":[{"count":0,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/3530\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=3530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=3530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=3530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}