{"id":3990,"date":"2012-03-15T00:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"http:\/\/prensa.wp2.mendoza.gov.ar\/?p=3990"},"modified":"2012-03-15T00:00:00","modified_gmt":"1970-01-01T00:00:00","slug":"la-cultura-como-herramienta-y-proceso-de-desarrollo","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/la-cultura-como-herramienta-y-proceso-de-desarrollo\/","title":{"rendered":"La cultura como herramienta y proceso de desarrollo"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><\/p>\n<p>Esta direcci&oacute;n del Ministerio de Cultura trabaja desde la concepci&oacute;n de la cultura como proceso de desarrollo personal y comunitario, implementando distintos programas en el territorio. Entre ellos destaca por la cantidad de integrantes y su fuerte desarrollo territorial, el Programa Provincial de Orquestas Infantiles, llevado a cabo en forma coordinada entre el Ministerio de Cultura y la Direcci&oacute;n de Educaci&oacute;n de Gesti&oacute;n Social de la Direcci&oacute;n General de Escuelas del Gobierno de Mendoza. En el marco del fortalecimiento de estos grupos se llevar&aacute; a cabo este viernes la entrega de nuevos instrumentos a las orquestas de Maip&uacute;, Luj&aacute;n de Cuyo y Godoy Cruz.<\/p>\n<p>En esta entrevista Carlos &Aacute;brego, quien est&aacute; al frente de la Direcci&oacute;n de Desarrollo Cultural, explica la importancia sociocultural de los programas que actualmente se implementan y c&oacute;mo se llevan a cabo en el territorio, al tiempo que anticipa aquellos proyectos que se han planificado para los pr&oacute;ximos meses.<\/p>\n<p>&ndash; &iquest;C&oacute;mo se ha previsto trabajar en la gesti&oacute;n con el Programa Provincial de Orquestas Infantiles?<\/p>\n<p>Respetando el proceso iniciado en 2008, y conscientes del crecimiento del programa hasta la fecha, se ha determinado con la Sra. Ministra profundizar el trabajo haciendo hincapi&eacute; en lo metodolog&iacute;a did&aacute;ctica y en la provisi&oacute;n de instrumentos faltantes o deteriorados.<\/p>\n<p>Actualmente existen 18 orquestas, una en cada departamento. Esto expresa el car&aacute;cter federal del programa, ya que cuenta con inserci&oacute;n real en toda la provincia.<\/p>\n<p>&ndash; &iquest;Se ha previsto trabajar en la creaci&oacute;n de nuevas orquestas o en el fortalecimiento de algunas?<\/p>\n<p>&ndash; Se apuesta al fortalecimiento de las existentes durante 2012 para encarar un nuevo proceso de creaci&oacute;n durante 2013.<\/p>\n<p>&ndash; &iquest;Qu&eacute; rol cumplen estos grupos en las comunidades en general y en la vida de los ni&ntilde;os y ni&ntilde;as en particular?<\/p>\n<p>Es un programa inclusivo que permite al ni&ntilde;o, ni&ntilde;a, su familia y comunidad tener contacto con aspectos de la cultura a la que no acceden f&aacute;cilmente.<\/p>\n<p>&ndash; &iquest;En qu&eacute; otros programas puntuales viene trabajando la Direcci&oacute;n de Desarrollo Cultural?<\/p>\n<p>&ndash; Por un lado, el programa de Teatro Comunitario. Actualmente, existen 8 proyectos en el Gran Mendoza llevados adelante por talleristas (de teatro y m&uacute;sica) en lugares de vulnerabilidad social. A trav&eacute;s del trabajo en com&uacute;n realizan actos u obras relacionadas con lo que las personas viven en su comunidad.<\/p>\n<p>Por otro lado, trabajamos con los juegos Culturales Evita que son como los cl&aacute;sicos del deporte pero en cultura. Sus categor&iacute;as son canto y baile y s&oacute;lo participan j&oacute;venes sub-16, sub-13 y adultos mayores. Anualmente se trabajan las finales provinciales y se acompa&ntilde;a la representaci&oacute;n de Mendoza a las finales nacionales.<\/p>\n<p>&ndash; &iquest;Qu&eacute; nuevos programas se perfilan desde la Direcci&oacute;n?<\/p>\n<p>A punto de ser presentados est&aacute;n el Programa Provincial de Murgas, Cultura en Contextos de Encierro, la Oficina de Accesibilidad e Inclusi&oacute;n y se reflota el Intercolegial de Teatro, competencia que exist&iacute;a antiguamente y estamos gestionando con DGE la posibilidad de un trabajo conjunto para volver a instalarlo.<\/p>\n<p>&ndash; &iquest;C&oacute;mo funcionar&aacute; el Programa Provincial de Murgas?<\/p>\n<p>&ndash; Partiendo de que las murgas se autosostienen, la idea es tener un programa que pueda complementar sus esfuerzos con materiales necesarios para su desarrollo (instrumentos, telas, repuestos, lentejuelas, flecos, talleristas).<\/p>\n<p>&ndash; &iquest;De qu&eacute; se trata &ldquo;Cultura en Contextos de Encierro&rdquo;?<\/p>\n<p>&ndash; Esto parte de un trabajo del Teatro Comunitario en el penal de San Felipe. Luego de algunas reuniones estamos trabajando con el Ministerio de Gobierno y Desarrollo Social un proyecto que contemple todos los penales, Dinaf y Cose, y que se ampl&iacute;e la mirada, incluyendo adem&aacute;s de teatro expresiones como guitarra, murgas, etc&eacute;tera.<\/p>\n<p>&ndash; &iquest;C&oacute;mo funcionar&aacute; la Oficina de inclusi&oacute;n y accesibilidad?<\/p>\n<p>&ndash; Se trata de un trabajo comprometido con aquellas personas con capacidades diferentes, para que tambi&eacute;n puedan disfrutar de los espect&aacute;culos p&uacute;blicos. Esto empez&oacute; a desarrollarse en el ciclo Verano Vendimia y en la Fiesta Nacional de la Vendimia.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"Esta direcci&oacute;n del Ministerio de Cultura trabaja desde la concepci&oacute;n de la cultura como proceso de desarrollo personal y comunitario, implementando distintos programas en el territorio. Entre ellos destaca por la cantidad de integrantes y su fuerte desarrollo territorial, el Programa Provincial de Orquestas Infantiles, llevado a cabo en forma coordinada entre el Ministerio de&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/la-cultura-como-herramienta-y-proceso-de-desarrollo\/\"><\/a>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/3990"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=3990"}],"version-history":[{"count":0,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/3990\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=3990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=3990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=3990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}