{"id":71578,"date":"2016-11-04T17:13:17","date_gmt":"2016-11-04T20:13:17","guid":{"rendered":"http:\/\/prensa.mendoza.gov.ar\/?p=71578"},"modified":"2016-11-04T17:13:17","modified_gmt":"2016-11-04T20:13:17","slug":"cultura-conformo-el-jurado-de-vendimia-2018","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/cultura-conformo-el-jurado-de-vendimia-2018\/","title":{"rendered":"Cultura conform\u00f3 el jurado de Vendimia 2018"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p><span style=\"color: #000000\">La Direcci&oacute;n de Producci&oacute;n Cultural y Vendimia, comunica la constituci&oacute;n del jurado, para el llamado a concurso p&uacute;blico para la propuesta de guion (con su correspondiente s&iacute;ntesis argumental incluida) propuesta o proyecto para la realizaci&oacute;n de la escenograf&iacute;a, direcci&oacute;n art&iacute;stica de la puesta en escena y equipo art&iacute;stico para el Acto Central, Segunda y Tercera Noche de la Fiesta Nacional de la Vendimia 2018, declaradas seg&uacute;n ley 6973 &ldquo;Patrimonio Cultural de la Provincia de Mendoza&rdquo;.<\/span><\/p>\n<p><span style=\"color: #000000\">Seg&uacute;n llamado oficial:<\/span><\/p>\n<p><span style=\"color: #000000\">Art&iacute;culo 21&ordm;: El jurado estar&aacute; conformado por 12 (doce) miembros con derecho a voto. Los que a su vez implican &aacute;reas de representatividad de las distintas especialidades art&iacute;sticas y&nbsp; t&eacute;cnicas que necesariamente&nbsp; deben participar en la selecci&oacute;n de las propuestas objeto del presente Llamado. Se aclara que en los rubros Danza (tres representantes), y&nbsp; M&uacute;sica (dos representantes) participar&aacute;n colegiadamente con m&aacute;s de un integrante con voz, pero con derecho a un &uacute;nico voto por rubro, esto es un voto por los representantes de asociaciones de la danza y un voto por los representantes de asociaciones de m&uacute;sicos.<\/span><\/p>\n<p><span style=\"color: #000000\">El Jurado que tendr&aacute; a cargo la selecci&oacute;n de la propuesta, est&aacute; integrado por un representante por cada organismo e instituci&oacute;n, por Secretar&iacute;a de Cultura, Carlos L&oacute;pez; por Asociaci&oacute;n Argentina de Actores, Ver&oacute;nica Lagiglia; por Secretar&iacute;a de Cultura, &Aacute;rea T&eacute;cnica Dar&iacute;o An&iacute;s; Facultad de Artes y Dise&ntilde;o UNCuyo, Gustavo Uano; Canal Acequia TV, Ariel Blasco; Historia &ndash; Antropolog&iacute;a Archivo General de la Provincia, Viviana Ceverino; Direcciones de Cultura de los Departamentos, Lucas Valsecchi; CORENAVE, Estela San Sebasti&aacute;n; Ex Directores de Fiestas Nacionales de la Vendimia, Alejandro Grigor; Ana Fajardo (Argentores); Asociaci&oacute;n Mendocina Profesionales de la Danza, Adriana Guajardo: Asociaci&oacute;n Movimiento por la Danza, Enzo De Luca; So&ntilde;arte, Marcelo Cristofoletti; Movimiento Independiente de M&uacute;sicos Mendocinos, Oscar Puebla y por el Sindicato de M&uacute;sicos de Cuyo, Carina P&aacute;ez.<\/span><\/p>\n<p><span style=\"color: #000000\">A continuaci&oacute;n se adjuntan los curr&iacute;culum de cada uno de los jurados<\/span><\/p>\n<p>Carlos L&oacute;pez <a href=\"https:\/\/goo.gl\/8F1RYa\" target=\"_blank\">https:\/\/goo.gl\/8F1RYa<\/a><\/p>\n<p>Ver&oacute;nica Lagiglia <a href=\"https:\/\/goo.gl\/nYVdzH\" target=\"_blank\">https:\/\/goo.gl\/nYVdzH<\/a><\/p>\n<p>Dar&iacute;o An&iacute;s <a href=\"https:\/\/goo.gl\/YYXldX\" target=\"_blank\">https:\/\/goo.gl\/YYXldX<\/a><\/p>\n<p>Gustavo Uano <a href=\"https:\/\/goo.gl\/3lK5qJ\" target=\"_blank\">https:\/\/goo.gl\/3lK5qJ<\/a><\/p>\n<p>Ariel Blasco <a href=\"https:\/\/goo.gl\/1VfqUU\" target=\"_blank\">https:\/\/goo.gl\/1VfqUU<\/a><\/p>\n<p>Viviana Ceverino <a href=\"https:\/\/goo.gl\/6E9XSU\" target=\"_blank\">https:\/\/goo.gl\/6E9XSU<\/a><\/p>\n<p>Lucas Valescchi <a href=\"https:\/\/goo.gl\/ssR6cw\" target=\"_blank\">https:\/\/goo.gl\/ssR6cw<\/a><\/p>\n<p>Estela San Sebasti&aacute;n <a href=\"https:\/\/goo.gl\/vgm80C\" target=\"_blank\">https:\/\/goo.gl\/vgm80C<\/a><\/p>\n<p>Alejandro Grigor <a href=\"https:\/\/goo.gl\/D1EPoZ\" target=\"_blank\">https:\/\/goo.gl\/D1EPoZ<\/a><\/p>\n<p>Adriana Guajardo <a href=\"https:\/\/goo.gl\/fF8nDv\" target=\"_blank\">https:\/\/goo.gl\/fF8nDv<\/a><\/p>\n<p>Enzo De Luca <a href=\"https:\/\/goo.gl\/dfXZK3\" target=\"_blank\">https:\/\/goo.gl\/dfXZK3<\/a><\/p>\n<p>Marcelo Cristofoletti <a href=\"https:\/\/goo.gl\/dfXZK3\" target=\"_blank\">https:\/\/goo.gl\/NkOF2c<\/a><\/p>\n<p>Oscar Puebla <a href=\"https:\/\/goo.gl\/GeFrzk\" target=\"_blank\">https:\/\/goo.gl\/GeFrzk<\/a><\/p>\n<p>Ana Fajardo (Argentores) <span style=\"color: #000000\">&nbsp;<span style=\"color: #0000ff\"><a style=\"color: #0000ff\" href=\"https:\/\/goo.gl\/6wGJMT\" target=\"_blank\">https:\/\/goo.gl\/6wGJMT<\/a><\/span><\/span><\/p>\n<p>Carina P&aacute;ez <a href=\"https:\/\/goo.gl\/36o13I\" target=\"_blank\">https:\/\/goo.gl\/36o13I<\/a><\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"En el marco, de la ley 6973, ser\u00e1n 12 los miembros del jurado que analizar\u00e1 y seleccionar\u00e1 las propuestas que se presenten a partir del pr\u00f3ximo a\u00f1o. Representan a las distintas especialidades art\u00edsticas y  t\u00e9cnicas que requiere el espect\u00e1culo. ","protected":false},"author":63,"featured_media":71579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,38],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/71578"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=71578"}],"version-history":[{"count":0,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/71578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media\/71579"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=71578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=71578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=71578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}