{"id":9755,"date":"2012-05-14T00:00:00","date_gmt":"2012-05-14T00:00:00","guid":{"rendered":"http:\/\/prensa.wp2.mendoza.gov.ar\/?p=9755"},"modified":"2012-05-14T00:00:00","modified_gmt":"2012-05-14T00:00:00","slug":"zandomeni-se-reunio-con-los-intendentes-del-este-para-tratar-los-residuos-solidos-urbanos","status":"publish","type":"post","link":"https:\/\/www.mendoza.gov.ar\/prensa\/zandomeni-se-reunio-con-los-intendentes-del-este-para-tratar-los-residuos-solidos-urbanos\/","title":{"rendered":"Zandomeni se reuni\u00f3 con los intendentes del Este para tratar los residuos s\u00f3lidos urbanos"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><p>El secretario de Ambiente y Desarrollo Sustentable, Ing. Marcos Zandomeni se reuni&oacute; con los Intendentes del Este para presentarles el Plan Provincial de Residuos S&oacute;lidos Urbanos.<\/p>\n<p>Esta importante iniciativa ha sido elaborada para Mendoza y tiene como objetivo principal lograr la implementaci&oacute;n de una Gesti&oacute;n Integral de Residuos S&oacute;lidos Urbanos (GIRSU) en todo el territorio provincial. Cabe destacar que el jueves 10 de mayo finalizo el primer taller sobre costos para la Gesti&oacute;n Integral de Residuos S&oacute;lidos Urbanos, GIRSU.<\/p>\n<p>Los objetivos de este Plan son: construir las infraestructuras necesarias, para el tratamiento y\/o disposici&oacute;n final  de los residuos s&oacute;lidos urbanos en toda la Provincia; regionalizar la Provincia y conformar Consorcios Intermunicipales de Gesti&oacute;n de Residuos, a los efectos de aprovechar la econom&iacute;a de escala; y colaborar con los Municipios de la Provincia en el desarrollo de acciones tendientes a la implementaci&oacute;n de una adecuada gesti&oacute;n de los RSU,  en las distintas etapas que componen la GIRSU.<\/p>\n<p>Entre los obras que deben llevarse a cabo para la implementaci&oacute;n del Plan de Gesti&oacute;n Integral de Residuos S&oacute;lidos Urbanos se destacan: la Estaci&oacute;n de Transferencia de Residuos de San Mart&iacute;n Distrito Alto Salvador (actual basural del Municipio), Estaci&oacute;n de Transferencia de Residuos de Santa Rosa. Recibir&aacute; los residuos de Santa Rosa y La Paz y el Centro de Disposici&oacute;n Final de Residuos de Rivadavia (relleno sanitario). Las obras mencionadas ser&aacute; financiadas con el 71%  aportado por el Gobierno de la Naci&oacute;n y el 21% aportado por el Gobierno Provincial.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"El secretario de Ambiente y Desarrollo Sustentable, Ing. Marcos Zandomeni se reuni&oacute; con los Intendentes del Este para presentarles el Plan Provincial de Residuos S&oacute;lidos Urbanos. Esta importante iniciativa ha sido elaborada para Mendoza y tiene como objetivo principal lograr la implementaci&oacute;n de una Gesti&oacute;n Integral de Residuos S&oacute;lidos Urbanos (GIRSU) en todo el territorio&#8230; <a class=\"view-article\" href=\"https:\/\/www.mendoza.gov.ar\/prensa\/zandomeni-se-reunio-con-los-intendentes-del-este-para-tratar-los-residuos-solidos-urbanos\/\"><\/a>","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/9755"}],"collection":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/comments?post=9755"}],"version-history":[{"count":0,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/posts\/9755\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/media?parent=9755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/categories?post=9755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mendoza.gov.ar\/prensa\/wp-json\/wp\/v2\/tags?post=9755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}